{"id":10493,"date":"2023-12-11T11:39:37","date_gmt":"2023-12-11T14:39:37","guid":{"rendered":"https:\/\/diariorepublica.com.ar\/web\/?p=10493"},"modified":"2023-12-11T11:39:38","modified_gmt":"2023-12-11T14:39:38","slug":"el-gobierno-revisara-las-contrataciones-y-exigira-la-presencialidad-plena-de-los-trabajadores-del-estado","status":"publish","type":"post","link":"https:\/\/diariorepublica.com.ar\/web\/index.php\/nacionales\/2023\/12\/11\/el-gobierno-revisara-las-contrataciones-y-exigira-la-presencialidad-plena-de-los-trabajadores-del-estado\/","title":{"rendered":"El Gobierno revisar\u00e1 las contrataciones y exigir\u00e1 la presencialidad plena de los trabajadores del Estado"},"content":{"rendered":"<p>El Gobierno nacional avanzar\u00e1 en la<strong>\u00a0revisi\u00f3n de \u00abcada una de las contrataciones en el Estado nacional\u00bb<\/strong>\u00a0para \u00abencontrar contrataciones irregulares\u00bb, indic\u00f3 el portavoz Manuel Adorni.<\/p>\n<p>El funcionario indic\u00f3, adem\u00e1s, que se realizar\u00e1 una inspecci\u00f3n de los \u00abcontratos con universidades\u00bb, entre otros puntos.<\/p>\n<p>Por \u00faltimo, Adorni se\u00f1al\u00f3 que desde el oficialismo se dispuso\u00a0<strong>que exigir\u00e1 la presencialidad plena de los trabajadores del Estado<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno nacional avanzar\u00e1 en la\u00a0revisi\u00f3n de \u00abcada una de las contrataciones en el Estado nacional\u00bb\u00a0para \u00abencontrar contrataciones irregulares\u00bb, indic\u00f3<\/p>\n","protected":false},"author":1,"featured_media":10494,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[4],"tags":[],"class_list":["post-10493","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/10493"}],"collection":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/comments?post=10493"}],"version-history":[{"count":1,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/10493\/revisions"}],"predecessor-version":[{"id":10495,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/10493\/revisions\/10495"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/media\/10494"}],"wp:attachment":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/media?parent=10493"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/categories?post=10493"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/tags?post=10493"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}