{"id":10699,"date":"2023-12-19T06:44:00","date_gmt":"2023-12-19T09:44:00","guid":{"rendered":"https:\/\/diariorepublica.com.ar\/web\/?p=10699"},"modified":"2023-12-19T11:44:58","modified_gmt":"2023-12-19T14:44:58","slug":"se-confirmo-el-equipo-de-gestion-del-ministerio-de-cultura-turismo-y-deporte","status":"publish","type":"post","link":"https:\/\/diariorepublica.com.ar\/web\/index.php\/sociedad\/2023\/12\/19\/se-confirmo-el-equipo-de-gestion-del-ministerio-de-cultura-turismo-y-deporte\/","title":{"rendered":"Se confirm\u00f3 el equipo de gesti\u00f3n del Ministerio de Cultura, Turismo y Deporte"},"content":{"rendered":"<p>Este lunes 18 de diciembre, la ministra de Cultura, Turismo y Deporte de Catamarca, Daiana Rold\u00e1n mantuvo una reuni\u00f3n con su recientemente conformado equipo de gesti\u00f3n, que marca continuidades con el trabajo que ya se ven\u00eda realizando, y tambi\u00e9n suma algunas incorporaciones.<\/p>\n<p>La arquitecta\u00a0<strong>Laura Maubec\u00edn<\/strong>, quien ven\u00eda desempe\u00f1\u00e1ndose como directora de Patrimonio y Museos asumi\u00f3 al frente de la\u00a0<strong>Secretar\u00eda de Gesti\u00f3n Cultural de la Provincia<\/strong>, desde donde se enfocar\u00e1 en trabajar la identidad cultural, fortaleciendo el patrimonio y la promoci\u00f3n de las artes, poniendo el foco en el trabajo territorial y articulado con los gestores culturales.<\/p>\n<p>Por su parte, la licenciada\u00a0<strong>Evangelina Quar\u00edn<\/strong>\u00a0continuar\u00e1 como\u00a0<strong>secretaria de Gesti\u00f3n Tur\u00edstica<\/strong>, cargo que ya ven\u00eda desempe\u00f1ando, y desde donde se pondr\u00e1 \u00e9nfasis en el desarrollo de productos tur\u00edsticos y en fortalecer la calidad de los servicios y la promoci\u00f3n tur\u00edstica que ya permiti\u00f3 posicionar el destino Catamarca.<\/p>\n<p>Del mismo modo, se confirm\u00f3 que\u00a0<strong>Monserrat Ram\u00edrez Toledo<\/strong>\u00a0seguir\u00e1 al frente de la\u00a0<strong>Secretar\u00eda de Administraci\u00f3n Financiera y Recursos Humanos<\/strong>\u00a0del Ministerio, \u00e1rea vital para el buen funcionamiento del Ministerio.<\/p>\n<p>Se incorpor\u00f3 al equipo de gesti\u00f3n\u00a0<strong>Exequiel D\u00edaz Elena<\/strong>, quien asumi\u00f3 en el cargo de\u00a0<strong>secretario de Deportes y Recreaci\u00f3n de la Provincia<\/strong>. D\u00edaz Elena viene de desempe\u00f1arse en el \u00e1rea de Deportes de la Municipalidad de la Capital y ahora se puso al frente de un \u00e1rea clave para trabajar tanto en la contenci\u00f3n social a trav\u00e9s del deporte y de los clubes como tambi\u00e9n en el acompa\u00f1amiento a la comunidad deportiva.<\/p>\n<p>Durante la reuni\u00f3n, Rold\u00e1n marc\u00f3 una serie de lineamientos de trabajo, dejando la premisa de \u201cser un equipo de gesti\u00f3n de puertas abiertas, cuidar y controlar los gastos en este contexto dif\u00edcil y trabajar articuladamente con todos los municipios y actores de la Cultura, el Turismo y el Deporte para poder cubrir territorialmente toda la provincia\u201d.<\/p>\n<p>Cada secretario plante\u00f3 prioridades para su \u00e1rea y se acord\u00f3 cerrar a la brevedad la agenda del verano para avanzar en la planificaci\u00f3n del 2024.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este lunes 18 de diciembre, la ministra de Cultura, Turismo y Deporte de Catamarca, Daiana Rold\u00e1n mantuvo una reuni\u00f3n con<\/p>\n","protected":false},"author":1,"featured_media":10700,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[3],"tags":[],"class_list":["post-10699","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sociedad"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/10699"}],"collection":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/comments?post=10699"}],"version-history":[{"count":1,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/10699\/revisions"}],"predecessor-version":[{"id":10701,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/10699\/revisions\/10701"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/media\/10700"}],"wp:attachment":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/media?parent=10699"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/categories?post=10699"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/tags?post=10699"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}