{"id":11582,"date":"2024-01-29T08:16:03","date_gmt":"2024-01-29T11:16:03","guid":{"rendered":"https:\/\/diariorepublica.com.ar\/web\/?p=11582"},"modified":"2024-01-29T08:16:04","modified_gmt":"2024-01-29T11:16:04","slug":"chubut-el-incendio-en-el-parque-nacional-los-alerces-ya-afecta-mas-de-1-000-hectareas","status":"publish","type":"post","link":"https:\/\/diariorepublica.com.ar\/web\/index.php\/nacionales\/2024\/01\/29\/chubut-el-incendio-en-el-parque-nacional-los-alerces-ya-afecta-mas-de-1-000-hectareas\/","title":{"rendered":"\u00a0Chubut:\u00a0el incendio en el Parque Nacional Los Alerces ya afecta m\u00e1s de 1.000 hect\u00e1reas"},"content":{"rendered":"<p class=\"first-letter-supercase-green\">El incendio desatado en el<strong>\u00a0Parque Nacional Los Alerces<\/strong>, y otras \u00e1reas de la provincia de\u00a0<strong>Chubut<\/strong>, contin\u00faa activo \u00aben todos los sectores\u00bb y ya\u00a0<strong>afect\u00f3 a m\u00e1s de 1.000 hect\u00e1reas<\/strong>, mientras es combatido por cientos de brigadistas, a quienes se sumar\u00e1n refuerzos, se inform\u00f3 este lunes.<\/p>\n<p>\u00ab<em><strong>El incendio, en estos momentos, contin\u00faa activo en todos sus sectores,<\/strong><\/em>\u00a0ya van aproximadamente, mas de mil hect\u00e1reas afectadas\u201d, sostuvo a la agencia T\u00e9lam, Mario C\u00e1rdenas, jefe del departamento de Incendios, Comunicaciones y Emergencias (ICE) del<strong>\u00a0Parque Nacional Los Alerces<\/strong>\u00a0(PNLA).<\/p>\n<p>Est\u00e1n previstos \u201cvarios d\u00edas de trabajo\u201d, agreg\u00f3 el funcionario.\u00a0\u00abLos brigadistas se encuentran \u201ctrabajando con l\u00edneas de herramientas de mano y equipos de agua, m\u00e1s medios a\u00e9reos como son dos\u00a0<strong>aviones hidrantes<\/strong>, tambi\u00e9n dos helic\u00f3pteros con \u00abhelibaldes\u00bb, que realizan lanzamientos de agua y un avi\u00f3n observador\u201d, \u00ab<strong>Seguimos d\u00e1ndole pelea<\/strong>\u00ab, se\u00f1al\u00f3 C\u00e1rdenas.<\/p>\n<p>C\u00e1rdenas advirti\u00f3 que las condiciones clim\u00e1ticas \u00abson adversas, porque<strong>\u00a0seguimos teniendo mucho viento y temperatura alta, lo que dificulta bastante las tareas<\/strong>\u00a0en el Parque Nacional\u00bb, el cual fue declarado sitio de patrimonio mundial por la Unesco en 2017.<\/p>\n<p>En tanto, un comunicado de Parques Nacionales precis\u00f3 este domingo que son 1.036 las hect\u00e1reas afectadas y que el fuego se mantiene activo en el l\u00edmite este del Parque Nacional Los Alerces,\u00a0<strong>\u00abquemando bosque nativo\u00bb. Agreg\u00f3 que \u00abno se registra infraestructura afectada\u00bb .<\/strong><\/p>\n<p>Por su parte, el<strong>\u00a0Ministerio del Interior<\/strong>\u00a0inform\u00f3 en un comunicado que \u201cparticipan del combate directo del fuego unos 144 agentes, dependientes de reparticiones que integran el Ministerio del Interior, a los que se suman otros 46 del\u00a0<strong>Servicio de Manejo del Fuego de la Provincia de Chubut<\/strong>\u201d.<\/p>\n<p>\u201cJunto a ellos contin\u00faan trabajando treinta y cinco brigadistas del Parque Nacional Los Alerces, treinta personas del Servicio Provincial de Manejo del Fuego de Chubut y bomberos voluntarios de<strong>\u00a0Trevelin y Esquel, Gendarmer\u00eda, Prefectura y Defensa civil<\/strong>\u00a0de Esquel\u201d, indicaron.<\/p>\n<p>El Servicio Nacional de Manejo del Fuego (SNMF) \u00abrefuerza los trabajos\u00bb, con dos aviones turboh\u00e9lices AT-802 con 3.000 litros de capacidad de descarga de agua cada uno, un avi\u00f3n observador Cessna 182, que facilita y mejora la evaluaci\u00f3n de los sectores del incendio, dos helic\u00f3pteros Bell, uno 407 y uno 412, aptos para el trabajo con helibalde y \u00abtraslado de personal a zonas de dif\u00edcil acceso\u00bb, a\u00f1adi\u00f3 el informe.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El incendio desatado en el\u00a0Parque Nacional Los Alerces, y otras \u00e1reas de la provincia de\u00a0Chubut, contin\u00faa activo \u00aben todos los<\/p>\n","protected":false},"author":1,"featured_media":11583,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[4],"tags":[],"class_list":["post-11582","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/11582"}],"collection":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/comments?post=11582"}],"version-history":[{"count":1,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/11582\/revisions"}],"predecessor-version":[{"id":11584,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/11582\/revisions\/11584"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/media\/11583"}],"wp:attachment":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/media?parent=11582"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/categories?post=11582"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/tags?post=11582"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}