{"id":11585,"date":"2024-01-29T08:18:10","date_gmt":"2024-01-29T11:18:10","guid":{"rendered":"https:\/\/diariorepublica.com.ar\/web\/?p=11585"},"modified":"2024-01-29T08:18:12","modified_gmt":"2024-01-29T11:18:12","slug":"ley-omnibus-diputados-reciben-ultima-version-del-proyecto-y-menem-se-reune-con-jefes-de-bloque","status":"publish","type":"post","link":"https:\/\/diariorepublica.com.ar\/web\/index.php\/politica\/2024\/01\/29\/ley-omnibus-diputados-reciben-ultima-version-del-proyecto-y-menem-se-reune-con-jefes-de-bloque\/","title":{"rendered":"Ley \u00f3mnibus: diputados reciben \u00faltima versi\u00f3n del proyecto y Menem se re\u00fane con jefes de bloque"},"content":{"rendered":"<article class=\"article-body article-body--first-paragraph content-protected-false\" data-td-script-src=\"https:\/\/www.ambito.com\/td\/modulos\/encuestas\/js\/function-embeds-min-version-1706501219.js\"><strong>Cien p\u00e1ginas menos<\/strong>. De 458 a 358 p\u00e1ginas en menos de una semana. Esta noche\u00a0<strong>comenz\u00f3 a circular entre los diputados la versi\u00f3n final del\u00a0proyecto de ley \u00f3mnibus<\/strong>\u00a0con los cambios definitivos, y los recortes del cap\u00edtulo fiscal que el viernes anuncio el ministro de Econom\u00eda<strong>\u00a0Luis Caputo.<\/strong><\/p>\n<\/article>\n<article class=\"article-body article-body--second-paragraph content-protected-false\">Pero adem\u00e1s hay un\u00a0<strong>ajuste en las facultades delegadas y desaparecen las emergencias previsional, de salud y de defensa<\/strong>. Es decir, con la \u00faltima poda que arras\u00f3 con la f\u00f3rmula de movilidad jubilatoria, de aprobarse esta versi\u00f3n de la ley Javier\u00a0<strong>Milei no podr\u00e1 luego gestionar desde el Ejecutivo un esquema de actualizaci\u00f3n de los haberes de los jubilados<\/strong>. Traducido: despeja suspicacias respecto a que el Gobierno avance luego, a trav\u00e9s de poderes especiales, con lo que no consigui\u00f3 en la mesa de negociaci\u00f3n parlamentaria.<\/p>\n<article class=\"article-body article-body--third-paragraph content-protected-false\">Este lunes se espera un d\u00eda intenso en las oficinas de <strong>Mart\u00edn Menem,<\/strong>\u00a0presidente de la\u00a0<strong>C\u00e1mara de Diputados<\/strong>, donde trajinar\u00e1n los jefes de los bloques dialoguistas:\u00a0<strong>Rodrigo De Loredo<\/strong>\u00a0(UCR),\u00a0<strong>Cristian Ritondo<\/strong>\u00a0(PRO) y\u00a0<strong>Miguel Pichetto<\/strong>\u00a0(Hacemos Coalici\u00f3n Federal), para convocar luego con los porotos en la mano.<strong>\u00a0\u201cVamos a apoyar\u201d, adelant\u00f3 a \u00c1mbito Ritondo.\u00a0<\/strong>El texto era le\u00eddo en paralelo con minuciosidad por radicales y por el espacio federal, m\u00e1xime tras las desprolijidades del \u00faltimo dictamen, donde diputados firmaron modificaciones que no estaban plasmadas en el papel, bajo la promesa de hacer cambios en el recinto.<\/p>\n<\/article>\n<article class=\"article-body article-body--fourth-paragraph content-protected-false\"><strong>Descontados los rechazos de Uni\u00f3n por la Patria y de la izquierda, los llamados dialoguistas son la llave para que Milei obtenga la ley, tras la derrota de la semana pasada, cuando Caputo baj\u00f3 retenciones, Ganancias, jubilaciones, entre otros \u00edtems<\/strong>, tras los cruces con los gobernadores, en especial los de Juntos por el Cambio, quienes no encontraron respuestas en la Casa Rosada y le torcieron el brazo a los libertarios. Ahora,\u00a0<strong>resta ver si eliminado el cap\u00edtulo habr\u00e1 mayores recortes a las provincias<\/strong>, pese a que los gobernadores no ven qu\u00e9 otras partidas podr\u00edan ser v\u00edctimas de la motosierra, que ya pas\u00f3 sin piedad por obra p\u00fablica y\u00a0<strong>ATNs.<\/strong><\/p>\n<\/article>\n<article class=\"article-body article-body--remaining-paragraph content-protected-false\">Los mandatarios volver\u00e1n a reunirse y tambi\u00e9n sumar\u00e1n al cordob\u00e9s\u00a0<strong>Mart\u00edn Llaryora,<\/strong>\u00a0que se volvi\u00f3 combativo pese a haber asegurado sillas claves en la administraci\u00f3n nacional, como Anses, Transporte o Banco Naci\u00f3n.<\/p>\n<p><strong>\u201cSi hay \u00e1nimo de apoyar, ya se avanz\u00f3 mucho. Si empezamos otra vez art\u00edculo por art\u00edculo, no. El gobierno hizo cambios aceptando las propuestas de distintos sectores. No sigan tirando de la cuerda\u201d, dijo el ministro del Interior, Guillermo Francos.\u00a0<\/strong>En el Gobierno entienden que los mandatarios de Juntos por el Cambio son voraces: que una vez obtenida una concesi\u00f3n piden otra. Y as\u00ed indefinidamente. Por otra parte, en la oposici\u00f3n observan que la negociaci\u00f3n con Francos luego se desautoriza desde el c\u00edrculo m\u00e1s \u00edntimo del Presidente.<\/p>\n<p>Por otra parte, las propias internas del radicalismo obstaculizan un voto homog\u00e9neo. El ala m\u00e1s dura, con Facundo Manes al frente, amaga con rechazar tambi\u00e9n en general. O acaso abstenerse para tomar distancia de UP. En el bloque de 23 diputados de Pichetto hay tambi\u00e9n posiciones m\u00e1s duras, como el de la socialista M\u00f3nica Fein o sectores de la Coalici\u00f3n C\u00edvica. Algunos provincialismo, por su parte, muestran menos predisposici\u00f3n tras las amenazas a los gobernadores, que calan hondo no solo en dirigentes, sino tambi\u00e9n en los habitantes de esas provincias, que sienten m\u00e1s identificaci\u00f3n con mandatarios locales que con el le\u00f3n libertario.<\/p>\n<p><strong>El nuevo texto tambi\u00e9n retoma el rol querellante de la Oficina Anticorrupci\u00f3n<\/strong>.\u00a0<strong>Respecto a las emergencias, quedan en pie la de las materias: econ\u00f3mica, financiera, fiscal, de seguridad, tarifaria, energ\u00e9tica y administrativa hasta el 31 de diciembre de 2024, con opci\u00f3n de pr\u00f3rroga por un a\u00f1o con aprobaci\u00f3n del Congreso.\u00a0<\/strong>Ya era sabida la eliminaci\u00f3n del articulado referido a blanqueo de capitales, retenciones, moratoria, Bienes Personales, la ley de Ganancias y f\u00f3rmula de actualizaci\u00f3n previsional.<\/p>\n<p>Asimismo,\u00a0<strong>se elimina el art\u00edculo que establec\u00eda la transferencia de activos del FGS de la Anses al Tesoro<\/strong>. Si bien Luis Caputo dej\u00f3 afuera el cap\u00edtulo fiscal,\u00a0<strong>se mantiene la parte de impuestos internos, transparencia fiscal, otras medidas, como la asignaci\u00f3n espec\u00edfica del impuesto PAIS.<\/strong><\/p>\n<p>El oficialismo tambi\u00e9n acept\u00f3 dejar afuera la facultad de disoluci\u00f3n para el caso de: empresas p\u00fablicas, universidades y entidades incluidas en el inciso c del art. 8 e la Ley 24.156 (INTA y Conicet).<\/p>\n<p>ambito.com<\/p>\n<\/article>\n<\/article>\n","protected":false},"excerpt":{"rendered":"<p>Cien p\u00e1ginas menos. De 458 a 358 p\u00e1ginas en menos de una semana. Esta noche\u00a0comenz\u00f3 a circular entre los diputados<\/p>\n","protected":false},"author":1,"featured_media":11586,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[12],"tags":[],"class_list":["post-11585","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/11585"}],"collection":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/comments?post=11585"}],"version-history":[{"count":1,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/11585\/revisions"}],"predecessor-version":[{"id":11587,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/11585\/revisions\/11587"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/media\/11586"}],"wp:attachment":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/media?parent=11585"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/categories?post=11585"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/tags?post=11585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}