{"id":12338,"date":"2024-02-28T06:51:00","date_gmt":"2024-02-28T09:51:00","guid":{"rendered":"https:\/\/diariorepublica.com.ar\/web\/?p=12338"},"modified":"2024-02-28T07:52:29","modified_gmt":"2024-02-28T10:52:29","slug":"el-gobierno-revisara-la-creacion-de-cinco-universidades-nacionales","status":"publish","type":"post","link":"https:\/\/diariorepublica.com.ar\/web\/index.php\/nacionales\/2024\/02\/28\/el-gobierno-revisara-la-creacion-de-cinco-universidades-nacionales\/","title":{"rendered":"El Gobierno revisar\u00e1 la creaci\u00f3n de cinco universidades nacionales"},"content":{"rendered":"<p>El Gobierno nacional encomend\u00f3\u00a0 que se lleve adelante <strong>una revisi\u00f3n de la creaci\u00f3n y el inicio de actividades acad\u00e9micas de cinco universidades nacionales.\u00a0<\/strong><\/p>\n<p>Se trata de las universidades del\u00a0<strong>Delta, Pilar, Ezeiza, R\u00edo Tercero y Madres de Plaza de Mayo.<\/strong>\u00a0La decisi\u00f3n la tom\u00f3 el presidente, Javier Milei, y la ejecut\u00f3 el Ministerio de Capital Humano, que encabeza\u00a0<strong>Sandra Pettovello<\/strong>, con la intervenci\u00f3n del subsecretario de Pol\u00edticas Universitarias de la Naci\u00f3n,\u00a0<strong>Alejandro Alvarez<\/strong><\/p>\n<p>Para este fin, la resoluci\u00f3n ministerial dispone \u00abestablecer el proceso de<strong>\u00a0revisi\u00f3n de la creaci\u00f3n e inicio de actividades acad\u00e9micas de las nuevas instituciones universitarias nacionales creadas por las Leyes Nros. 27.727, 27.728, 27.729, 27.730 y 27.731<\/strong>\u00a0con el fin de determinar el efectivo cumplimiento del procedimiento para su creaci\u00f3n y funcionamiento objetivo\u201d.<\/p>\n<p>A su vez, en el documento se indica: \u00abAtendiendo a razones de dar cumplimiento a lo establecido en las leyes vigentes, de evitar la duplicaci\u00f3n y superposici\u00f3n de estructuras jer\u00e1rquicas y de garantizar que la oferta educativa cumpla con la calidad y pertinencia debida,\u00a0<strong>resulta necesaria la adopci\u00f3n de medidas tendientes a revisar el inicio de actividades acad\u00e9micas de las Casas de Altos Estudios antes mencionadas<\/strong>\u00ab.<\/p>\n<p>Con esta acci\u00f3n, el Gobierno tiene como objetivo \u00abdeterminar si el procedimiento administrativo exigido por la Ley de Educaci\u00f3n Superior para crear nuevas universidades fue debidamente cumplido,\u00a0<strong>si las condiciones all\u00ed establecidas fueron realmente satisfechas y se encuentren debidamente documentadas y si la pertinencia, oportunidad y la previsi\u00f3n del cr\u00e9dito presupuestario correspondiente, en base a un estudio de factibilidad, aval\u00f3 la iniciativa<\/strong>\u00ab.<\/p>\n<p>En tanto, al aprobarse el a\u00f1o pasado en el Congreso la construcci\u00f3n de las universidades en cuesti\u00f3n,\u00a0<strong>el bloque de La Libertad Avanza (LLA), que encabezaba Milei, hab\u00eda votado en contra de la medida<\/strong>. Al tiempo que el peronismo y la izquierda fueron los que garantizaron su aprobaci\u00f3n.<\/p>\n<p>Por aquel entonces estaba prevista la creaci\u00f3n de tres universidades m\u00e1s. De esta manera, se quintuplicar\u00eda la cantidad de alumnos en los estudios superiores.<\/p>\n<p>NA<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno nacional encomend\u00f3\u00a0 que se lleve adelante una revisi\u00f3n de la creaci\u00f3n y el inicio de actividades acad\u00e9micas de<\/p>\n","protected":false},"author":1,"featured_media":12339,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[4],"tags":[],"class_list":["post-12338","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/12338"}],"collection":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/comments?post=12338"}],"version-history":[{"count":1,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/12338\/revisions"}],"predecessor-version":[{"id":12340,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/12338\/revisions\/12340"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/media\/12339"}],"wp:attachment":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/media?parent=12338"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/categories?post=12338"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/tags?post=12338"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}