{"id":16107,"date":"2024-06-25T00:52:00","date_gmt":"2024-06-25T03:52:00","guid":{"rendered":"https:\/\/diariorepublica.com.ar\/web\/?p=16107"},"modified":"2024-06-25T07:54:13","modified_gmt":"2024-06-25T10:54:13","slug":"brasil-empato-frente-a-costa-rica","status":"publish","type":"post","link":"https:\/\/diariorepublica.com.ar\/web\/index.php\/deportes\/2024\/06\/25\/brasil-empato-frente-a-costa-rica\/","title":{"rendered":"Brasil empat\u00f3 frente a Costa Rica"},"content":{"rendered":"<p><strong>Brasil tuvo un flojo debut de Copa Am\u00e9rica, ya que pese a tener el protagonismo y crear varias situaciones de gol apenas pudo empatar 0 a 0 frente a Costa Rica<\/strong>, en un partido disputado en el\u00a0<strong>SoFi Stadium de California,<\/strong>\u00a0por la primera fecha del\u00a0<strong>Grupo D<\/strong>\u00a0de la<strong>\u00a0Copa Am\u00e9rica 2024,\u00a0<\/strong>que se lleva a cabo en los Estados Unidos.<\/p>\n<p>El elenco brasile\u00f1o tuvo chances como para abrir el marcador, \u00a0pero las dilapid\u00f3, e incluso<strong>\u00a0el \u00e1rbitro mexicano C\u00e9sar Arturo Ramos anul\u00f3 a instancias del VAR un pol\u00e9mico gol convertido por Marquinhos, a los 29 minutos del primer tiempo, por posici\u00f3n adelantada de Rodrygo, quien lo hab\u00eda asistido al peinar el bal\u00f3n.<\/strong><\/p>\n<p><strong>El Grupo D lo lidera<\/strong>\u00a0<strong>Colombia con 3 puntos, Brasil y Costa Rica tienen 1 y Paraguay cierra sin unidades.<\/strong><\/p>\n<p>El elenco \u00abverdeamarelho\u00bb enfrentar\u00e1 este viernes al conjunto \u00abguaran\u00ed\u00bb, a partir de las 22:00, mientras que la selecci\u00f3n centroamericana har\u00e1 lo propio el mismo d\u00eda, pero a las 19:00, ante el equipo \u00abcafetero\u00bb.<\/p>\n<p>Brasil arranc\u00f3 con todo y tuvo el protagonismo frente a un rival que lo esper\u00f3 en su cancha, dispuesto a intentar meter alg\u00fan contragolpe.<\/p>\n<p>Ya a los 11 minutos\u00a0<strong>se lo perdi\u00f3 Rodrygo<\/strong>, quien recibi\u00f3 un pase de Lucas Paquet\u00e1 y tras eludir en el \u00e1rea a los defensores sac\u00f3 un remate que se fue apenas desviado.<\/p>\n<p>A los 21, un contragolpe comandado por<strong>\u00a0Vin\u00edcius J\u00fanior\u00a0<\/strong>termin\u00f3 en un disparo mordido de Lucas Paquet\u00e1, mientras que tres minutos m\u00e1s tarde<strong>\u00a0Raphinha\u00a0<\/strong>qued\u00f3 solo con el arquero de Costa Rica,\u00a0<strong>Patrick Sequeira<\/strong>, y defini\u00f3 de volea, pero el remate le sali\u00f3 a las manos del guardameta.<\/p>\n<p>Parec\u00eda que a los 29 minutos Brasil se pon\u00eda en ventaja con un gol de Marquinhos, tras una peinada de Rodrygo, pero el \u00e1rbitro mexicano C\u00e9sar Arturo Ramos anul\u00f3 la conquista a instancias del VAR por posici\u00f3n adelantada del atacante del Real Madrid cuando cabece\u00f3 el bal\u00f3n.<\/p>\n<p>En el complemento, el conjunto \u201cverdeamarelho\u201d no detuvo sus intenciones de atacar, mientras que Costa Rica apel\u00f3 a un juego algo m\u00e1s dura para frenar los avances de su rival y se gan\u00f3 un par de tarjetas amarillas.<\/p>\n<p>A los 17 minutos se salvaron los centroamericanos\u00a0<strong>cuando Lucas Paquet\u00e1 sac\u00f3 un disparo que se estrell\u00f3 en el palo.<\/strong><\/p>\n<p>Brasil no ces\u00f3 en su af\u00e1n por abrir el marcador y casi lo logra otras dos veces. Primero a los 26 minutos, cuando el defensor de Costa Rica\u00a0<strong>Haxzel Quir\u00f3s\u00a0<\/strong>cabece\u00f3 un centro contra su propio arco y\u00a0<strong>Sequeira la desvi\u00f3 con lo justo al c\u00f3rner.<\/strong><\/p>\n<p>Y luego, a los 33, mediante un tremendo disparo de<strong>\u00a0Guilherme Arana<\/strong>\u00a0que el arquero \u00abTico\u00bb desvi\u00f3 de manera fant\u00e1stica.<\/p>\n<p>En los minutos finales Brasil tuvo una m\u00e1s y otra vez con\u00a0<strong>Rodrygo<\/strong>, quien aprovech\u00f3 un pase en profundidad, le gan\u00f3 en la salida al arquero,\u00a0<strong>pero se qued\u00f3 sin \u00e1ngulo para rematar\u00a0<\/strong>y tuvo que mandar un centro que fue rechazado por la defensa del elenco centroamericano.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Brasil tuvo un flojo debut de Copa Am\u00e9rica, ya que pese a tener el protagonismo y crear varias situaciones de<\/p>\n","protected":false},"author":1,"featured_media":16109,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[9],"tags":[],"class_list":["post-16107","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/16107"}],"collection":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/comments?post=16107"}],"version-history":[{"count":1,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/16107\/revisions"}],"predecessor-version":[{"id":16110,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/16107\/revisions\/16110"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/media\/16109"}],"wp:attachment":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/media?parent=16107"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/categories?post=16107"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/tags?post=16107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}