{"id":16313,"date":"2024-07-01T09:54:27","date_gmt":"2024-07-01T12:54:27","guid":{"rendered":"https:\/\/diariorepublica.com.ar\/web\/?p=16313"},"modified":"2024-07-01T09:54:29","modified_gmt":"2024-07-01T12:54:29","slug":"nueva-empresa-de-maquinaria-vial-y-servicios-se-instalo-en-valle-viejo","status":"publish","type":"post","link":"https:\/\/diariorepublica.com.ar\/web\/index.php\/sociedad\/2024\/07\/01\/nueva-empresa-de-maquinaria-vial-y-servicios-se-instalo-en-valle-viejo\/","title":{"rendered":"Nueva empresa de maquinaria vial y servicios se instal\u00f3 en Valle Viejo"},"content":{"rendered":"<p>El gobernador Ra\u00fal Jalil particip\u00f3 en la inauguraci\u00f3n de la sucursal de la empresa \u201cAmerican Vial\u201d, destacada en el rubro de maquinaria y servicios para la miner\u00eda y agroindustria, que abre las puertas laborales a decenas de catamarque\u00f1os. La empresa est\u00e1 estrat\u00e9gicamente ubicada en Avenida Circunvalaci\u00f3n, en las inmediaciones de la Ruta Nacional 33.<\/p>\n<p>El acto de inauguraci\u00f3n cont\u00f3 con la presencia del vicegobernador Rub\u00e9n Dusso; la intendenta de Valle Viejo, Susana Zenteno; el ministro de Industria, Comercio y Empleo, Sebasti\u00e1n Caria; el ministro de Miner\u00eda, Marcelo Mur\u00faa, y el ministro de Salud, Lucas Zampieri, entre otras autoridades. Adem\u00e1s, el evento reuni\u00f3 a empresarios que expresaron su apoyo al gerente del local, el catamarque\u00f1o Bruno Vega.<\/p>\n<p>Ra\u00fal, por su parte, brind\u00f3 un discurso en el que destac\u00f3 el constante crecimiento que experimenta la provincia en diversos sectores y mencion\u00f3 que \u201cesta radicaci\u00f3n posibilitar\u00e1 contar con mejores -y de manera directa- servicios en sectores estrat\u00e9gicos para nosotros como lo son la obra p\u00fablica, la miner\u00eda y la agroindustria\u201d.<\/p>\n<p>En sus palabras, Bruno Vega expres\u00f3: \u201cMe comprometo a seguir trabajando para que crezca la planta de empleados, para que agrandemos otra nave\u201d. Tambi\u00e9n anhel\u00f3 que la empresa \u201csea para Valle Viejo un lugar de proyecci\u00f3n, que se empiece a poblar todo y que, como en toda ciudad grande, entremos y sea toda \u00e1rea industrial. Apostamos a Catamarca\u201d.<\/p>\n<p>American Vial es una reconocida empresa nacional que durante los \u00faltimos a\u00f1os ha sido una de las principales proveedoras de maquinaria vial y servicios para miner\u00eda y agroindustria en el pa\u00eds. Ahora tiene su sede en Catamarca para aportar al desarrollo de estos sectores.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El gobernador Ra\u00fal Jalil particip\u00f3 en la inauguraci\u00f3n de la sucursal de la empresa \u201cAmerican Vial\u201d, destacada en el rubro<\/p>\n","protected":false},"author":1,"featured_media":16314,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[3],"tags":[],"class_list":["post-16313","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sociedad"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/16313"}],"collection":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/comments?post=16313"}],"version-history":[{"count":1,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/16313\/revisions"}],"predecessor-version":[{"id":16315,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/16313\/revisions\/16315"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/media\/16314"}],"wp:attachment":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/media?parent=16313"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/categories?post=16313"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/tags?post=16313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}