{"id":19478,"date":"2024-10-19T00:15:00","date_gmt":"2024-10-19T03:15:00","guid":{"rendered":"https:\/\/diariorepublica.com.ar\/web\/?p=19478"},"modified":"2024-10-19T16:46:40","modified_gmt":"2024-10-19T19:46:40","slug":"velez-se-llevo-un-punto-del-monumental-y-sigue-en-lo-mas-alto","status":"publish","type":"post","link":"https:\/\/diariorepublica.com.ar\/web\/index.php\/deportes\/2024\/10\/19\/velez-se-llevo-un-punto-del-monumental-y-sigue-en-lo-mas-alto\/","title":{"rendered":"V\u00e9lez se llev\u00f3 un punto del Monumental y sigue en lo m\u00e1s alto"},"content":{"rendered":"<article id=\"article-post\" class=\"first\">\n<div class=\"cuerpo\" data-twitter-link=\"https:\/\/twitter.com\/intent\/tweet?url=https:\/\/www.diariopopular.com.ar\/c811286&amp;via=poopulardiario&amp;related=Popular&amp;text=\">\n<p><strong>Un punto de oro se llev\u00f3 V\u00e9lez Sarsfield del estadio M\u00e1s Monumental donde igual\u00f3 con River Plate 1-1 en un partido de alternativas cambiantes: por momentos fue favorable al conjunto de Liniers, pero por otros, como en el cierre, su rival, que jug\u00f3 con mayor\u00eda de titulares, fue el que estuvo cerca de dar vuelta la historia.<\/strong><\/p>\n<\/div>\n<\/article>\n<article id=\"article-post\">\n<div class=\"cuerpo\" data-twitter-link=\"https:\/\/twitter.com\/intent\/tweet?url=https:\/\/www.diariopopular.com.ar\/c811286&amp;via=poopulardiario&amp;related=Popular&amp;text=\">\n<p>Braian Romero puso en ventaja al equipo orientado por Gustavo Quinteros a los 25 minutos del primer tiempo, igualando las cosas\u00a0<strong>Miguel Borja<\/strong>\u00a0de tiro penal a los 4 de la parte complementaria al concretar un penal cometido por el goleador velezano.<\/p>\n<p>Con el punto obtenido, el\u00a0<em>Fort\u00edn\u00a0<\/em>estir\u00f3 a seis unidades la ventaja sobre sus escoltas, Hurac\u00e1n, que ma\u00f1ana visitar\u00e1 a Uni\u00f3n en Santa Fe, y Talleres de C\u00f3rdoba, que el domingo ir\u00e1 al estadio Diego Armando Maradona de La Paternal para chocar con Argentinos Juniors.<\/p>\n<p>River se mantuvo a once puntos del l\u00edder cuando quedan 27 en disputa y ser\u00e1 dif\u00edcil que puede recuperar tanto terreno. Pero en la tabla anual se mantiene en el tercer lugar, en zona de Copa Libertadores, a la que igual podr\u00e1 acceder si es que gana la edici\u00f3n de este a\u00f1o.<\/p>\n<div id=\"embed8_wrap\" class=\"embed_cont type_freetext\" contenteditable=\"false\">\n<div id=\"embed8_content\" class=\"embed_content\">\n<div id=\"embed8_embed\">\n<div class=\"video_container\"><iframe loading=\"lazy\" class=\"video_iframe\" src=\"https:\/\/www.youtube.com\/embed\/gK_qNvtxELY\" width=\"100%\" height=\"360\" frameborder=\"0\" scrolling=\"no\" data-gtm-yt-inspected-11=\"true\" data-mce-fragment=\"1\"><\/iframe><\/div>\n<\/div>\n<\/div>\n<div id=\"embed8_epigrafe\" class=\"embed_epigrafe\"><\/div>\n<div id=\"embed8_copyright\" class=\"embed_copyright\"><\/div>\n<\/div>\n<p>Pareja result\u00f3 la primera mitad en la que el\u00a0<em>Millonario<\/em>, que finalmente utiliz\u00f3 a muchos titulares, fue el que intent\u00f3 m\u00e1s, pero termin\u00f3 sufriendo ante un adversario que cuando le dan espacios suele aprovecharlos con jugadores muy talentosos.<\/p>\n<p>Y as\u00ed fue que a los 25 Romero recibi\u00f3 un centro desde la derecha de Claudio Aquino, se lanz\u00f3 en una especie de palomita y le dio con el pecho para mandar la pelota a la red y poner el 1-0, que era un premio excesivo en ese momento.<\/p>\n<p>Y lo sigui\u00f3 siendo hasta cierre del segmento inicial, ya que de ah\u00ed en adelante River fue el que asumi\u00f3 decidamente el control del juego, pero no estuvo fino a la hora de definir. A este equipo de Gallardo le viene costando resolver cuando los equipos le cierran los caminos de tres cuartos de cancha hacia adelante. Hasta ah\u00ed todo bien, pero los goles suelen tardar en llegar.<\/p>\n<p>Estuvo cerca el colombiano Miguel Borja en un mano a mano, pero fall\u00f3 y adem\u00e1s estaba adelantado. No hubo mucho m\u00e1s: la pelota termin\u00f3 siendo de River pero las jugadas de riesgo frente al arco de Tom\u00e1s Matchiori escasearon.<\/p>\n<p>El empate lleg\u00f3 a los 4 del complemento, tras tres minutos de deliberaci\u00f3n del VAR. Miguel Borja quebr\u00f3 su sequ\u00eda al concretar un penal que hab\u00eda cometido Romero al intentar despejar de cabeza un c\u00f3rner para finalmente darle con el brazo.<\/p>\n<p>El gol del empate abri\u00f3 el partido y los dos tuvieron sus chances para llevarse los tres puntos. Estuvo cerca V\u00e9lez en un principio, al generar tres opciones muy claras: un mano a mano que Armani le gan\u00f3 a Francisco Pizzini, un quite salvador de Santiago Sim\u00f3n cuando Tiago Fern\u00e1ndez se aprestaba a definir y un tiro libre de Aquino que se fue cerca.<\/p>\n<p>Pero River tambi\u00e9n tuvo las suyas en el tramo decisivo del encuentro en el que la visita perdi\u00f3 protagonismo. Y sobre el final cerca estuvo de ganarlo en una acci\u00f3n de pelota parada que termin\u00f3 con Facundo Colidio estrellando el bal\u00f3n en la parte exterior de la red cuando estaba completamente solo.<\/p>\n<p>Terminaron sumando un punto cada uno y no estuvo mal. Aunque el resultado termin\u00f3 favoreciendo m\u00e1s al\u00a0<em>Fort\u00edn<\/em>, que sum\u00f3 en una cancha complicada y pr\u00e1cticamente se sac\u00f3 de encima a uno de los mejores equipos del f\u00fatbol argentino, que de ahora en m\u00e1s apuntar\u00e1 a otra cosa, al menos por un par de semanas.<\/p>\n<p>V\u00e9lez seguir\u00e1 en lo m\u00e1s alto esta fecha. Super\u00f3 un complicado obst\u00e1culo y parece encaminado a la meta para festejar un campeonato que, por lo hecho hasta el momento, merece largamente.<\/p>\n<\/div>\n<\/article>\n","protected":false},"excerpt":{"rendered":"<p>Un punto de oro se llev\u00f3 V\u00e9lez Sarsfield del estadio M\u00e1s Monumental donde igual\u00f3 con River Plate 1-1 en un<\/p>\n","protected":false},"author":1,"featured_media":19479,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[9],"tags":[],"class_list":["post-19478","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/19478"}],"collection":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/comments?post=19478"}],"version-history":[{"count":1,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/19478\/revisions"}],"predecessor-version":[{"id":19480,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/19478\/revisions\/19480"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/media\/19479"}],"wp:attachment":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/media?parent=19478"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/categories?post=19478"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/tags?post=19478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}