{"id":20544,"date":"2024-11-28T12:01:40","date_gmt":"2024-11-28T15:01:40","guid":{"rendered":"https:\/\/diariorepublica.com.ar\/web\/?p=20544"},"modified":"2024-11-28T12:01:42","modified_gmt":"2024-11-28T15:01:42","slug":"punto-violeta-abre-una-vivienda-para-mujeres-victimas-de-violencia","status":"publish","type":"post","link":"https:\/\/diariorepublica.com.ar\/web\/index.php\/sociedad\/2024\/11\/28\/punto-violeta-abre-una-vivienda-para-mujeres-victimas-de-violencia\/","title":{"rendered":"Punto Violeta abre una vivienda para mujeres v\u00edctimas de violencia"},"content":{"rendered":"<p>Este viernes a las 10:00 en calle Rivadavia 252, la Secretar\u00eda de Mujeres, G\u00e9nero y Diversidad de la Municipalidad de la Capital, que conduce Gabriela Molina, inaugurar\u00e1\u00a0<strong>La Casa \u201cPunto Violeta\u201d<\/strong>, un centro municipal integral transitorio de protecci\u00f3n a mujeres v\u00edctimas de la violencia machista.<\/p>\n<p>Este nuevo lugar tiene por objetivo brindar alojamiento, contenci\u00f3n y asistencia a mujeres y sus hijos a la vez que se garantizar\u00e1 la protecci\u00f3n y desarrollo de los ni\u00f1os, quienes estar\u00e1n asistidos por un equipo de profesionales, asegurando la confidencialidad en todas las etapas del proceso.<\/p>\n<p>El acto contar\u00e1 con la presencia del Intendente, Gustavo Saadi quien cortar\u00e1 las cintas de este espacio, dise\u00f1ado para proteger a mujeres v\u00edctimas de violencia de g\u00e9nero, que no cuentan con un entorno seguro y libre para promover su autonom\u00eda.<\/p>\n<p>Para poder ingresar al nuevo edificio las personas deber\u00e1n ser mayor de edad y que est\u00e9n atravesando una situaci\u00f3n de violencia o de alta vulnerabilidad haciendo una evaluaci\u00f3n de riesgo, dentro de las 72 horas h\u00e1biles.<\/p>\n<p>El plazo de alojamiento se dar\u00e1 entre tres a 15 d\u00edas, superando esta instancia se realizar\u00e1 la derivaci\u00f3n a un lugar de abordaje provincial. Una vez que las mujeres abandonen la vivienda se les instalar\u00e1 un dispositivo de prevenci\u00f3n Punto Violeta, para asegurar que la persona se encuentra fuera de riesgo.<\/p>\n<p>Cabe destacar que, en la vivienda trabajan cuidadores en tres turnos, como as\u00ed tambi\u00e9n \u00e1reas sociales, legales y psicol\u00f3gicas y personal de seguridad en forma permanente.<\/p>\n<p>La Secretaria, Gabriela Molina, agradeci\u00f3 al intendente Saadi, seguir apostando por pol\u00edticas p\u00fablicas que favorezcan a las mujeres, \u201chace dos a\u00f1os que estamos trabajando en este proyecto que brindar\u00e1 asistencia y contenci\u00f3n a m\u00e1s mujeres en nuestra Capital\u201d, agreg\u00f3.<\/p>\n<p><strong>\u00a0<\/strong><strong>Edificio<\/strong><\/p>\n<p>El espacio cuenta con un hall de ingreso, dos habitaciones, con camas cuchetas, camas simples y cunitas, en caso de recibir a ni\u00f1os muy peque\u00f1os. Los espacios tienen placard, aire acondicionado, calefactor y ba\u00f1o privado.\u00a0 A su vez, en la sala de estar cuentan con televisores, heladeras, cocina y lavarropas autom\u00e1tico, en tanto que hay un patio con juegos para ni\u00f1os.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este viernes a las 10:00 en calle Rivadavia 252, la Secretar\u00eda de Mujeres, G\u00e9nero y Diversidad de la Municipalidad de<\/p>\n","protected":false},"author":1,"featured_media":20545,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[3],"tags":[],"class_list":["post-20544","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sociedad"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/20544"}],"collection":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/comments?post=20544"}],"version-history":[{"count":1,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/20544\/revisions"}],"predecessor-version":[{"id":20546,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/20544\/revisions\/20546"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/media\/20545"}],"wp:attachment":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/media?parent=20544"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/categories?post=20544"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/tags?post=20544"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}