{"id":21834,"date":"2025-02-14T11:46:01","date_gmt":"2025-02-14T14:46:01","guid":{"rendered":"https:\/\/diariorepublica.com.ar\/web\/?p=21834"},"modified":"2025-02-14T11:46:03","modified_gmt":"2025-02-14T14:46:03","slug":"hamas-anuncio-que-liberara-al-argentino-iair-horn-junto-a-otros-dos-rehenes","status":"publish","type":"post","link":"https:\/\/diariorepublica.com.ar\/web\/index.php\/internacionales\/2025\/02\/14\/hamas-anuncio-que-liberara-al-argentino-iair-horn-junto-a-otros-dos-rehenes\/","title":{"rendered":"Ham\u00e1s anunci\u00f3 que liberar\u00e1 al argentino Iair Horn junto a otros dos rehenes"},"content":{"rendered":"<p>La agrupaci\u00f3n terrorista Ham\u00e1s confirm\u00f3 los nombres de los tres rehenes que liberar\u00e1 el pr\u00f3ximo s\u00e1bado como parte del sexto intercambio de rehenes israel\u00edes por prisioneros palestinos. Se trata de el argentino Iair Horn, el estadounidense-israel\u00ed Sagui Dekel-Chen y Alexandre Sasha Troufanov, secuestrados durante el ataque del 7 de octubre de 2023.<\/p>\n<p>Iair Horn tiene 46 a\u00f1os y se fue a Israel en el a\u00f1o 2000. Su hermano Eitan tambi\u00e9n fue secuestrado durante el ataque del 7 de octubre al kibutz Nir Oz, ubicado en Israel, pero \u00e9l no figura en el listado de rehenes que ser\u00e1n liberados en los pr\u00f3ximos d\u00edas.<\/p>\n<p>Este ser\u00e1 el sexto canje de rehenes por presos palestinos luego de que se acordara la tregua con Israel el pasado mi\u00e9rcoles 15 de enero. Por su parte, la Yihad Isl\u00e1mica Palestina dijo que pretende liberar a una persona este s\u00e1bado, aunque no aclararon si est\u00e1 dentro del listado de los tres que ya fue anunciado o se sumar\u00eda como un cuarto liberado en total.<\/p>\n<p>Dentro del grupo de tres que ser\u00e1 liberado el s\u00e1bado se encuentra el argentino Iair Horn, qui\u00e9n se fue del pa\u00eds con la crisis del 2000, cuando ten\u00eda 22 a\u00f1os. Hincha de Atlanta, estudi\u00f3 en la escuela Scholem Aleijem de Villa Crespo, donde coordinaba en su juventud uno de los grupos de Nofesh<\/p>\n<p>A pesar de la alegr\u00eda por la liberaci\u00f3n de Iair, la preocupaci\u00f3n sigue persente ya que su hermano Eitan &#8211; tambi\u00e9n secuestrado el 7 de octubre de 2023 &#8211; no figura en el listado de rehenes pr\u00f3ximos a liberar.<\/p>\n<p>La liberaci\u00f3n llegar\u00e1 luego de una semana de tensiones entre Israel y Ham\u00e1s en referencia al cronograma de liberaciones acordados. El portavoz terrorista Abdel Latif al-Qanou afirm\u00f3: \u00ab\u201cEstamos comprometidos con la tregua y obligamos a la ocupaci\u00f3n a respetarla plenamente\u201d,<\/p>\n<p>Por su parte, el ministro de Defensa, Israel Katz, fue categ\u00f3rico: \u201cSi Hamas no entrega a los rehenes, la guerra continuar\u00e1 hasta la derrota total de la organizaci\u00f3n terrorista y la liberaci\u00f3n de todos los secuestrados\u201d.<\/p>\n<p>ambito.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La agrupaci\u00f3n terrorista Ham\u00e1s confirm\u00f3 los nombres de los tres rehenes que liberar\u00e1 el pr\u00f3ximo s\u00e1bado como parte del sexto<\/p>\n","protected":false},"author":1,"featured_media":21835,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[6],"tags":[],"class_list":["post-21834","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacionales"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/21834"}],"collection":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/comments?post=21834"}],"version-history":[{"count":1,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/21834\/revisions"}],"predecessor-version":[{"id":21836,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/21834\/revisions\/21836"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/media\/21835"}],"wp:attachment":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/media?parent=21834"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/categories?post=21834"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/tags?post=21834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}