{"id":22452,"date":"2025-03-12T09:53:14","date_gmt":"2025-03-12T12:53:14","guid":{"rendered":"https:\/\/diariorepublica.com.ar\/web\/?p=22452"},"modified":"2025-03-12T09:53:16","modified_gmt":"2025-03-12T12:53:16","slug":"cuenta-regresiva-para-el-inicio-de-la-carrera-de-medicina-avanzan-las-obras-en-el-centro-de-formacion","status":"publish","type":"post","link":"https:\/\/diariorepublica.com.ar\/web\/index.php\/sociedad\/2025\/03\/12\/cuenta-regresiva-para-el-inicio-de-la-carrera-de-medicina-avanzan-las-obras-en-el-centro-de-formacion\/","title":{"rendered":"Cuenta regresiva para el inicio de la carrera de Medicina: avanzan las obras en el Centro de Formaci\u00f3n"},"content":{"rendered":"<p>En el marco de una reuni\u00f3n encabezada por el gobernador Ra\u00fal Jalil en Casa de Gobierno, junto al rector de la Universidad Nacional de Catamarca (UNCa), Oscar Arellano, y el decano de la Facultad de Salud, Omar Barrionuevo, se informaron los detalles sobre la puesta en condiciones del edificio donde funcionar\u00e1 la carrera de Medicina.<\/p>\n<p>El inicio del cursado est\u00e1 confirmado para abril de 2025 en el edificio del Instituto de Formaci\u00f3n Profesional N\u00b01, ubicado en la zona suroeste de la Capital. En este sentido, las autoridades comunicaron que las obras de adecuaci\u00f3n, tanto \u00e1ulicas como de laboratorio, avanzan a buen ritmo y seg\u00fan lo planificado, cumpliendo con las normas de infraestructura necesarias para la formaci\u00f3n de los futuros profesionales de la salud.<\/p>\n<p>Las obras y acciones para la implantaci\u00f3n de la carrera de Medicina, que tiene m\u00e1s de 1700 inscriptos, se realizan bajo el trabajo articulado entre las diferentes \u00e1reas involucradas.<\/p>\n<p>Asimismo, las autoridades confirmaron que el dictado de los talleres de oficio que pertenecen al Centro de Formaci\u00f3n N\u00b01 se continuar\u00e1n dictando en un sector del edificio tal cual se lo ven\u00eda haciendo a\u00f1os anteriores.<\/p>\n<p>Tambi\u00e9n participaron de la reuni\u00f3n los ministros Juan Marchetti (Infraestructura y Obras Civiles), Dalmacio Mera (Educaci\u00f3n) y Lucas Zampieri (Salud), y la vicerrectora de la UNCa, Elina Silvera de Buenader.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el marco de una reuni\u00f3n encabezada por el gobernador Ra\u00fal Jalil en Casa de Gobierno, junto al rector de<\/p>\n","protected":false},"author":1,"featured_media":22454,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[3],"tags":[],"class_list":["post-22452","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sociedad"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/22452"}],"collection":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/comments?post=22452"}],"version-history":[{"count":1,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/22452\/revisions"}],"predecessor-version":[{"id":22455,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/22452\/revisions\/22455"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/media\/22454"}],"wp:attachment":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/media?parent=22452"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/categories?post=22452"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/tags?post=22452"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}