{"id":22862,"date":"2025-04-03T07:45:17","date_gmt":"2025-04-03T10:45:17","guid":{"rendered":"https:\/\/diariorepublica.com.ar\/web\/?p=22862"},"modified":"2025-04-03T07:45:20","modified_gmt":"2025-04-03T10:45:20","slug":"las-hermanas-de-maradona-y-veronica-ojeda-declaran-en-una-audiencia-clave","status":"publish","type":"post","link":"https:\/\/diariorepublica.com.ar\/web\/index.php\/nacionales\/2025\/04\/03\/las-hermanas-de-maradona-y-veronica-ojeda-declaran-en-una-audiencia-clave\/","title":{"rendered":"Las hermanas de Maradona y Ver\u00f3nica Ojeda declaran en una audiencia clave"},"content":{"rendered":"<p>Ana, Rita y Claudia Maradona, las hermanas de Diego Armando, y Ver\u00f3nica Ojeda declaran hoy en la octava audiencia del juicio oral por la muerte del ex jugador.<\/p>\n<p>Fernando Burlando, el asesor de Dalma y Gianinna, lo confirm\u00f3 en di\u00e1logo con la Agencia Noticias Argentinas.<\/p>\n<p>La audiencia comenzar\u00e1 a las 9:30 en el Tribunal Oral en lo Criminal N\u00b03 de San Isidro.<\/p>\n<p>Por su parte, Ana, Rita y Claudia fueron citadas a indagatoria junto al abogado Mat\u00edas Morla, Maximiliano Pomargo y Sandra Iampolsky en el caso por la presunta apropiaci\u00f3n ilegal de las marcas del campe\u00f3n del mundo en M\u00e9xico 1986, como por ejemplo Satvicca S.A.<\/p>\n<p>Los imputados deber\u00e1n responder preguntas los d\u00edas 8, 10, 15, 16, 22 y 24 de abril en el Juzgado Nacional en lo Criminal y Correccional N\u00b043 de Capital Federal.<\/p>\n<p>Las hermanas y el resto de los involucrados enfrentan cargos por supuesta defraudaci\u00f3n y administraci\u00f3n fraudulenta.<\/p>\n<p>Declararon otros peritos de la autopsia<br \/>\nEl m\u00e9dico tanat\u00f3logo y especialista en medicina legal, Alejandro Vega, destac\u00f3 que el coraz\u00f3n de Maradona estaba \u00abexcedido de tama\u00f1o\u00bb y pesaba unos 503 gramos, cuando lo normal es el \u00f3rgano de una persona de 60 a\u00f1os ronde entre 250 y 300 gramos.<\/p>\n<p>En este sentido, el especialista, de la morgue judicial, sostuvo que el examen revel\u00f3 que el coraz\u00f3n ten\u00eda \u00abuna isquemia de larga data\u00bb, producto de la ausencia de irrigaci\u00f3n y ox\u00edgeno.<\/p>\n<p>Por su parte, Ezequiel Ventosi resalt\u00f3 que durante la autopsia no se encontraron rastros de alcohol y drogas tras las muestras de sangre y orina, aunque se detect\u00f3 un \u00abcuadro avanzado de cirrosis\u00bb, una situaci\u00f3n ratificada por Silvana De Piero.<\/p>\n<p>\u00abEl ri\u00f1\u00f3n ten\u00eda la funci\u00f3n alterada y el coraz\u00f3n ten\u00eda l\u00edquido, estaba edematizado\u00bb, agreg\u00f3 la facultativa, al tiempo que se\u00f1al\u00f3: \u00abEl edema es acumulaci\u00f3n de agua en las c\u00e9lulas y lo encontramos en el cerebro, el coraz\u00f3n y los pulmones\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ana, Rita y Claudia Maradona, las hermanas de Diego Armando, y Ver\u00f3nica Ojeda declaran hoy en la octava audiencia del<\/p>\n","protected":false},"author":1,"featured_media":22863,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[4],"tags":[],"class_list":["post-22862","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/22862"}],"collection":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/comments?post=22862"}],"version-history":[{"count":1,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/22862\/revisions"}],"predecessor-version":[{"id":22864,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/22862\/revisions\/22864"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/media\/22863"}],"wp:attachment":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/media?parent=22862"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/categories?post=22862"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/tags?post=22862"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}