{"id":2398,"date":"2023-05-04T07:53:15","date_gmt":"2023-05-04T10:53:15","guid":{"rendered":"https:\/\/diariorepublica.com.ar\/web\/?p=2398"},"modified":"2023-05-04T07:53:17","modified_gmt":"2023-05-04T10:53:17","slug":"san-lorenzo-y-palestino-repartieron-puntos-en-rancagua","status":"publish","type":"post","link":"https:\/\/diariorepublica.com.ar\/web\/index.php\/deportes\/2023\/05\/04\/san-lorenzo-y-palestino-repartieron-puntos-en-rancagua\/","title":{"rendered":"San Lorenzo y Palestino repartieron puntos en Rancagua"},"content":{"rendered":"<article id=\"article-post\" class=\"first\">\n<div class=\"cuerpo\" data-twitter-link=\"https:\/\/twitter.com\/intent\/tweet?url=https:\/\/www.diariopopular.com.ar\/c712497&amp;via=poopulardiario&amp;related=Popular&amp;text=\">\n<p><strong>San Lorenzo y Palestino empataron sin goles en el estadio El Teniente de Rancagua, Chile, por la tercera fecha del Grupo H de la Copa Sudamericana:\u00a0<\/strong>el Cicl\u00f3n termin\u00f3 con un hombre menos por la expulsi\u00f3n de Federico Gattoni.<\/p>\n<\/div>\n<\/article>\n<article id=\"article-post\">\n<div class=\"cuerpo\" data-twitter-link=\"https:\/\/twitter.com\/intent\/tweet?url=https:\/\/www.diariopopular.com.ar\/c712497&amp;via=poopulardiario&amp;related=Popular&amp;text=\">\n<p>Si el partido no se jugaba, no hac\u00eda mucha diferencia.\u00a0<strong>Tr\u00e1mite chato, aburrido, parejo y trabado. Tanto que casi no hubo situaciones de gol.<\/strong>\u00a0Dos equipos que no se caracterizan por intentar jugar con la pelota, y en un campo de juego paup\u00e9rrimo que no ayud\u00f3 para nada,\u00a0<strong>dieron como resultado un 0-0 que resume a la perfecci\u00f3n lo que pas\u00f3: nada.<\/strong><\/p>\n<div id=\"embed50_wrap\" class=\"embed_cont type_freetext\" contenteditable=\"false\">\n<div id=\"embed50_content\" class=\"embed_content\">\n<div id=\"embed50_embed\">\n<div class=\"video_container\"><iframe loading=\"lazy\" class=\"video_iframe\" src=\"https:\/\/www.youtube.com\/embed\/ky9XuuPjUHY\" width=\"100%\" height=\"360\" frameborder=\"0\" scrolling=\"no\" data-gtm-yt-inspected-11=\"true\" data-mce-fragment=\"1\"><\/iframe><\/div>\n<\/div>\n<\/div>\n<div id=\"embed50_epigrafe\" class=\"embed_epigrafe\"><\/div>\n<div id=\"embed50_copyright\" class=\"embed_copyright\"><\/div>\n<\/div>\n<p><strong>Casi 70 minutos tard\u00f3 en aparecer la primera ocasi\u00f3n de peligro, y fue para el equipo local.<\/strong>\u00a0Es que durante casi todo el partido, los arqueros fueron espectadores de lujo.\u00a0<strong>San Lorenzo<\/strong>\u00a0no suele arriesgar de visitante, y Palestino, quiz\u00e1s m\u00e1s por falta de recursos colectivos e individuales que por no tener la intenci\u00f3n, tampoco gener\u00f3 mucho.<\/p>\n<p>El argentino\u00a0<strong>Salas<\/strong>\u00a0fue el \u00fanico que logr\u00f3 incomodar a la defensa del Cicl\u00f3n con corridas, pero estando solo contra tres torres duras como el cemento, como lo son P\u00e9rez, Gattoni y Hern\u00e1ndez, cuanto mucho pudo ganar faltas. \u00c9l fue quien a los 25 minutos del complemento tuvo la primera situaci\u00f3n concreta. Antes, algunos centros llovidos de ambos equipos, pero nada m\u00e1s.<\/p>\n<p>Para el segundo tiempo<strong>\u00a0Rub\u00e9n Dar\u00edo Insua\u00a0<\/strong>meti\u00f3 a Agust\u00edn Martegani y lo junt\u00f3 con Nahuel Barrios, una sociedad que ilusiona al hincha de\u00a0<strong>San Lorenzo\u00a0<\/strong>pero poco se ha podido disfrutar en cancha. Sin embargo, dur\u00f3 poco y no dio resultado, y el Perrito termin\u00f3 siendo sustituido. Con su salida, los cuervos perdieron al \u00fanico desfachatado, atrevido, rebelde, que con la pelota iba decidido hacia adelante.<\/p>\n<p><strong>Luego del aviso de Salas, San Lorenzo reaccion\u00f3 y tuvo dos oportunidades claras, ambas por cabezazos de Vombergar.<\/strong>\u00a0En el primero de ellos, Bareiro captur\u00f3 el rebote pero se lo err\u00f3 abajo del arco. Palestino tambi\u00e9n respondi\u00f3 con un buen remate de larga distancia de V\u00e9jar que Batalla mand\u00f3 al c\u00f3rner.<\/p>\n<p>El Cicl\u00f3n sab\u00eda que si aceleraba un poco pod\u00eda ganarlo, incluso luego de quedarse con 10 por una zonza\u00a0<strong>expulsi\u00f3n de Gattoni<\/strong>, quien estando amonestado se tir\u00f3 con ambos pies a buscar una pelota controlada por el arquero Rigamonti. Vale remarcar de todos modos que la amarilla fue exagerada. Y aunque lo busc\u00f3, fue tan t\u00edmida esa b\u00fasqueda que no le alcanz\u00f3.<\/p>\n<p>El punto le sirve m\u00e1s a\u00a0<strong>San Lorenzo,<\/strong> teniendo en cuenta que jug\u00f3 de visitante y ambos quedan con 4 unidades, por detr\u00e1s del l\u00edder Fortaleza, que si el jueves le gana a Estudiantes de M\u00e9rida mete un pie en octavos. En la pr\u00f3xima fecha, el Cicl\u00f3n visitar\u00e1 a los brasile\u00f1os, pero antes recibir\u00e1 a Defensa y Justicia por la Liga Profesional, el lunes.<\/p>\n<\/div>\n<\/article>\n","protected":false},"excerpt":{"rendered":"<p>San Lorenzo y Palestino empataron sin goles en el estadio El Teniente de Rancagua, Chile, por la tercera fecha del<\/p>\n","protected":false},"author":1,"featured_media":2399,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[9],"tags":[],"class_list":["post-2398","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/2398"}],"collection":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/comments?post=2398"}],"version-history":[{"count":1,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/2398\/revisions"}],"predecessor-version":[{"id":2400,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/2398\/revisions\/2400"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/media\/2399"}],"wp:attachment":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/media?parent=2398"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/categories?post=2398"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/tags?post=2398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}