{"id":24564,"date":"2025-06-24T06:40:00","date_gmt":"2025-06-24T09:40:00","guid":{"rendered":"https:\/\/diariorepublica.com.ar\/web\/?p=24564"},"modified":"2025-06-24T07:42:01","modified_gmt":"2025-06-24T10:42:01","slug":"adios-a-cuota-simple-lanzan-un-nuevo-plan-de-cuotas-que-incluira-productos-importados","status":"publish","type":"post","link":"https:\/\/diariorepublica.com.ar\/web\/index.php\/economia\/2025\/06\/24\/adios-a-cuota-simple-lanzan-un-nuevo-plan-de-cuotas-que-incluira-productos-importados\/","title":{"rendered":"Adi\u00f3s a Cuota Simple: lanzan un nuevo plan de cuotas que incluir\u00e1 productos importados"},"content":{"rendered":"<p><strong>Empresarios pymes lanzar\u00e1n su propio programa de financiamiento<\/strong>\u00a0en cuotas con tasas competitivas para apuntalar las ventas tras el vencimiento del programa \u201cCuota Simple\u201d.<\/p>\n<p>El programa estar\u00e1 operativo desde el\u00a0<strong>1\u00b0 de julio<\/strong>\u00a0e incluye a casi medio centenar de sectores, seg\u00fan anunci\u00f3 la\u00a0<strong>Confederaci\u00f3n Argentina de la Mediana Empresa (CAME)<\/strong>.<\/p>\n<p>El plan se denomina\u00a0<strong>Cuota MiPyME<\/strong>\u00a0y estar\u00e1 gestionado por la empresa\u00a0<strong>Payway<\/strong>.<\/p>\n<p>La iniciativa busca impulsar el\u00a0<strong>consumo y las ventas<\/strong>\u00a0en los comercios y est\u00e1 dirigida a las pymes que cuenten con su certificado vigente (seg\u00fan padr\u00f3n de la\u00a0<strong>Sepyme<\/strong>).<\/p>\n<p>El nuevo programa contar\u00e1 con\u00a0<strong>3 \u00f3 6 cuotas<\/strong>\u00a0con tasas promocionales, contemplar\u00e1 los mismos rubros de Cuota Simple e incorporar\u00e1 productos importados. Las cuotas no tendr\u00e1n un\u00a0<strong>tope de financiaci\u00f3n<\/strong>.<\/p>\n<p>\u201cEs fundamental para el peque\u00f1o y mediano comerciante contar con financiamiento en cuotas con baja carga de intereses para ganar competitividad frente a las promociones y las ofertas de las grandes superficies. Continuar\u00e1n las cuotas para los comercios minoristas pymes de todo el pa\u00eds\u201d, dijo el presidente de CAME,\u00a0<strong>Ricardo Diab<\/strong>.<\/p>\n<p>Por su parte, el Chief Business Officer de Payway,\u00a0<strong>Emiliano Porciani<\/strong>, enfatiz\u00f3 que \u201cacompa\u00f1amos y cuidamos el negocio de las pymes para que puedan seguir creciendo. Por esta raz\u00f3n, nos parece fundamental que puedan seguir teniendo alternativas de financiaci\u00f3n en cuotas a tasas competitivas, sin que la terminaci\u00f3n de Cuota Simple los afecte\u201d.<\/p>\n<p>As\u00ed, los comercios que ya operan con\u00a0<strong>Cuota Simple<\/strong>\u00a0con Payway acceder\u00e1n autom\u00e1ticamente al programa\u00a0<strong>Cuotas MiPyME<\/strong>\u00a0y tendr\u00e1n las mismas opciones de financiaci\u00f3n (13 para 3 cuotas y 16 para 6 cuotas).<\/p>\n<p>Los negocios de Payway que no est\u00e1n adheridos a Cuota Simple podr\u00e1n hacerlo ingresando a la\u00a0<strong>p\u00e1gina de la empresa<\/strong>.<\/p>\n<p>Los rubros incluidos son:<\/p>\n<ul>\n<li><strong>Indumentaria y calzado:<\/strong>\u00a0ropa, zapatos, accesorios, etc.<\/li>\n<li><strong>L\u00ednea blanca:<\/strong>\u00a0electrodom\u00e9sticos grandes como heladeras, lavarropas, etc.<\/li>\n<li><strong>Peque\u00f1os electrodom\u00e9sticos:<\/strong>\u00a0tostadoras, licuadoras, etc.<\/li>\n<li><strong>Muebles y colchones:<\/strong>\u00a0art\u00edculos para el hogar.<\/li>\n<li><strong>Bicicletas y motos:<\/strong>\u00a0rodados para transporte personal.<\/li>\n<li><strong>Materiales y herramientas para la construcci\u00f3n:<\/strong>\u00a0arena, cemento, ladrillos, etc.<\/li>\n<li><strong>Equipamiento m\u00e9dico:<\/strong>\u00a0equipos de terapia respiratoria, sillas de ruedas, etc.<\/li>\n<li><strong>Servicios de cuidado personal:<\/strong>\u00a0peluquer\u00eda, est\u00e9tica.<\/li>\n<li><strong>Turismo:<\/strong>\u00a0pasajes, hoteles, excursiones.<\/li>\n<li><strong>Servicios de instalaci\u00f3n de alarmas:<\/strong>\u00a0seguridad electr\u00f3nica.<\/li>\n<li><strong>Servicios de organizaci\u00f3n de eventos:<\/strong>\u00a0catering, fotograf\u00eda.<\/li>\n<li><strong>Libros y art\u00edculos de librer\u00eda:<\/strong>\u00a0materiales para estudio y lectura.<\/li>\n<li><strong>Espect\u00e1culos y eventos culturales:<\/strong>\u00a0entradas a conciertos, obras de teatro, etc.<\/li>\n<li><strong>Tel\u00e9fonos celulares con tecnolog\u00eda 4G y 5G:<\/strong>\u00a0dispositivos m\u00f3viles.<\/li>\n<li><strong>Computadoras, notebooks y tablets:<\/strong>\u00a0dispositivos electr\u00f3nicos.<\/li>\n<li><strong>Anteojos y lentes de contacto:<\/strong>\u00a0art\u00edculos de \u00f3ptica.<\/li>\n<li><strong>Artefactos de iluminaci\u00f3n:<\/strong>\u00a0l\u00e1mparas, focos, etc.<\/li>\n<li><strong>Instrumentos musicales:<\/strong>\u00a0pianos, guitarras, etc.<\/li>\n<li><strong>Juguetes:<\/strong>\u00a0art\u00edculos para ni\u00f1os.<\/li>\n<li><strong>Maquinaria y herramientas:<\/strong>\u00a0para uso dom\u00e9stico o profesional.<\/li>\n<li><strong>Neum\u00e1ticos, accesorios y repuestos:<\/strong>\u00a0para autom\u00f3viles y motos.<\/li>\n<li><strong>Servicios educativos:<\/strong>\u00a0cursos, capacitaciones.<\/li>\n<li><strong>Servicios de reparaci\u00f3n:<\/strong>\u00a0de veh\u00edculos, electrodom\u00e9sticos, etc.<\/li>\n<li><strong>Kit para la conexi\u00f3n a servicios de agua y cloacas:<\/strong>\u00a0para instalaciones domiciliarias.<\/li>\n<li><strong>Kit para la conexi\u00f3n a servicios de internet satelital:<\/strong>\u00a0para zonas sin acceso a internet tradicional.<\/li>\n<li><strong>Seguridad electr\u00f3nica:<\/strong>\u00a0c\u00e1maras de videovigilancia, alarmas, etc.<\/li>\n<\/ul>\n<p>NA<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Empresarios pymes lanzar\u00e1n su propio programa de financiamiento\u00a0en cuotas con tasas competitivas para apuntalar las ventas tras el vencimiento del<\/p>\n","protected":false},"author":1,"featured_media":24565,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[5],"tags":[],"class_list":["post-24564","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/24564"}],"collection":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/comments?post=24564"}],"version-history":[{"count":1,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/24564\/revisions"}],"predecessor-version":[{"id":24566,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/24564\/revisions\/24566"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/media\/24565"}],"wp:attachment":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/media?parent=24564"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/categories?post=24564"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/tags?post=24564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}