{"id":27330,"date":"2025-10-24T16:35:00","date_gmt":"2025-10-24T19:35:00","guid":{"rendered":"https:\/\/diariorepublica.com.ar\/web\/?p=27330"},"modified":"2025-10-24T09:37:29","modified_gmt":"2025-10-24T12:37:29","slug":"river-vs-independiente-rivadavia-por-la-copa-argentina-desde-las-2210","status":"publish","type":"post","link":"https:\/\/diariorepublica.com.ar\/web\/index.php\/deportes\/2025\/10\/24\/river-vs-independiente-rivadavia-por-la-copa-argentina-desde-las-2210\/","title":{"rendered":"River vs. Independiente Rivadavia, por la Copa Argentina desde las 22:10"},"content":{"rendered":"<p>River e Independiente Rivadavia se enfrentar\u00e1n este pr\u00f3ximo viernes a las 22:15 en el estadio Mario Alberto Kempes de C\u00f3rdoba, buscando un lugar en la final de la Copa Argentina. Mirando la otra llave, el ganador se medir\u00e1 con Argentinos Juniors, que elimin\u00f3 a Belgrano y es el primer finalista.<\/p>\n<p>Para el equipo de Marcelo Gallardo, la Copa Argentina representa un objetivo crucial, especialmente tras la reciente eliminaci\u00f3n de la Copa Libertadores en cuartos de final a manos de Palmeiras. El acceso a esta instancia lleg\u00f3 luego de derrotar a Racing en cuartos, con el solitario gol de Maximiliano Salas en un partido cargado de morbo.<\/p>\n<p>Adem\u00e1s de la b\u00fasqueda del t\u00edtulo, este certamen es una v\u00eda fundamental para River en su clasificaci\u00f3n a la pr\u00f3xima Libertadores. Si bien actualmente se ubica segundo en la tabla anual, la situaci\u00f3n es ajustada: Boca tiene un partido pendiente contra Barracas Central y, si lo gana, podr\u00eda relegar al Millonario al tercer puesto, que otorga un lugar de repechaje al certamen continental.<\/p>\n<p>En el \u00e1mbito local, River se ubica en el 5\u00ba puesto de la Zona B del Torneo Clausura con 21 unidades. No obstante, llega a esta semifinal con un impulso an\u00edmico tras su \u00faltima victoria 2-0 sobre Talleres en el Kempes, un resultado que cort\u00f3 una dif\u00edcil racha de seis derrotas en siete encuentros.<\/p>\n<p>Por su parte,<b>\u00a0Independiente Rivadavia accedi\u00f3 a esta instancia frente al conjunto de N\u00fa\u00f1ez tras\u00a0superar a Tigre por 3-1 en los cuartos de final<\/b>. Sin embargo, en el Torneo Clausura, el equipo atraviesa un momento irregular, ya que no consigue una victoria desde fines de agosto, sumando desde entonces dos derrotas y cuatro empates, con la\u00a0<b>reciente ca\u00edda frente a Banfield como local<\/b>.<\/p>\n<p>A pesar de este presente, los dirigidos por Alfredo Berti apostar\u00e1n todo a la Copa Argentina, que\u00a0<b>podr\u00eda significar el primer t\u00edtulo oficial de su historia<\/b>. En el Clausura, el equipo de Cuyo\u00a0<b>se ubica en el 13\u00ba lugar de su zona con 12 puntos<\/b>, fuera de la clasificaci\u00f3n a octavos de final. En la tabla anual, la Lepra se encuentra a seis unidades de distancia de los puestos que otorgan acceso a la Copa Sudamericana.<\/p>\n<ul>\n<li><u>Hora<\/u>: 22.15.<\/li>\n<li><u>TV<\/u>: TyC Sports.<\/li>\n<li><u>\u00c1rbitro<\/u>: Andr\u00e9s Gariano.<\/li>\n<li><u>Estadio<\/u>: Mario Alberto Kempes.<\/li>\n<\/ul>\n<p>tycsports.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>River e Independiente Rivadavia se enfrentar\u00e1n este pr\u00f3ximo viernes a las 22:15 en el estadio Mario Alberto Kempes de C\u00f3rdoba,<\/p>\n","protected":false},"author":1,"featured_media":27331,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[9],"tags":[],"class_list":["post-27330","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/27330"}],"collection":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/comments?post=27330"}],"version-history":[{"count":1,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/27330\/revisions"}],"predecessor-version":[{"id":27332,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/27330\/revisions\/27332"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/media\/27331"}],"wp:attachment":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/media?parent=27330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/categories?post=27330"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/tags?post=27330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}