{"id":27336,"date":"2025-10-24T11:02:37","date_gmt":"2025-10-24T14:02:37","guid":{"rendered":"https:\/\/diariorepublica.com.ar\/web\/?p=27336"},"modified":"2025-10-24T11:02:39","modified_gmt":"2025-10-24T14:02:39","slug":"veda-electoral-cuales-son-las-prohibiciones-enmarcadas-en-la-ley","status":"publish","type":"post","link":"https:\/\/diariorepublica.com.ar\/web\/index.php\/sociedad\/2025\/10\/24\/veda-electoral-cuales-son-las-prohibiciones-enmarcadas-en-la-ley\/","title":{"rendered":"Veda electoral: cu\u00e1les son las prohibiciones enmarcadas en la ley"},"content":{"rendered":"<p>La veda electoral comenz\u00f3 a las 8 de hoy, por lo que no se podr\u00e1 difundir publicidad electoral ni realizar actos p\u00fablicos pol\u00edticos, entre otras actividades, hasta el cierre de los comicios.<\/p>\n<p>Esta medida est\u00e1 enmarcada en el C\u00f3digo Electoral Nacional (Ley 19.945), que contiene las prohibiciones de las actividades que no pueden llevarse a cabo tanto en las horas previas como durante la jornada electoral, con el objetivo de garantizar un proceso electoral transparente y proteger el voto de los ciudadanos.<\/p>\n<p>Algunas de esas actividades, circunscriptas en el art\u00edculo 71 de la ley, son los <strong>actos de proselitismo pol\u00edtico; la publicidad de partidos o candidatos; la publicaci\u00f3n de encuestas y sondeos preelectorales y la venta de bebidas alcoh\u00f3licas (desde la noche anterior a la elecci\u00f3n)<\/strong>, entre otras acciones. En caso de que alguna persona incumpla la veda puede recibir en sanciones.<\/p>\n<p>Por otra parte, tambi\u00e9n quedan tambi\u00e9n vedados los <strong>espect\u00e1culos ya sean \u201c<i>al aire libre, en recintos cerrados, fiestas teatrales, deportivas y toda clase de reuniones p\u00fablicas que no se refieran al acto electoral\u201d<\/i>\u00a0durante el desarrollo de la jornada electoral y hasta pasadas tres horas de finalizado el acto.<\/strong><\/p>\n<p>Con respecto al consumo de alcohol, queda eliminada tambi\u00e9n la posibilidad de que permanezcan abiertas \u201clas casas destinadas al expendio de cualquier clase de bebidas alcoh\u00f3licas\u201d hasta despu\u00e9s de tres horas del cierre del comicios, a las 18 del domingo.<\/p>\n<p>Tampoco pueden mantenerse abiertos locales partidarios \u201c<i>dentro de un radio de 80 metros<\/i>\u201d del lugar en que se lleven a cabo las mesas de votos; en caso de que sucediera, la Junta Electoral Nacional \u201c<i>podr\u00e1 disponer su cierre transitorio\u201d.<\/i><\/p>\n<p>Por \u00faltimo, no se podr\u00e1 tomar fotograf\u00edas de la Boleta \u00danica de Papel (BUP) durante el proceso de votaci\u00f3n.<\/p>\n<p>En el caso de que alguna persona no cumpliera con la veda electoral, al llevar a cabo cualquiera de las actividades suspendidas durante el periodo establecido, podr\u00edan sufrir penas de prisi\u00f3n de 1 a 3 a\u00f1os, as\u00ed como aquellos que violen el secreto del voto o quienes ofrezcan o entreguen boletas dentro de un radio de 80 metros de las mesas de votaci\u00f3n.<\/p>\n<p>Por \u00faltimo, se podr\u00e1 aplicar una pena de 1 a 10 a\u00f1os de prisi\u00f3n a quienes cometan alguno de los delitos penados que se encuentran detallados en el C\u00f3digo Electoral Nacional.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La veda electoral comenz\u00f3 a las 8 de hoy, por lo que no se podr\u00e1 difundir publicidad electoral ni realizar<\/p>\n","protected":false},"author":1,"featured_media":27337,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[3],"tags":[],"class_list":["post-27336","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sociedad"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/27336"}],"collection":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/comments?post=27336"}],"version-history":[{"count":1,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/27336\/revisions"}],"predecessor-version":[{"id":27338,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/27336\/revisions\/27338"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/media\/27337"}],"wp:attachment":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/media?parent=27336"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/categories?post=27336"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/tags?post=27336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}