{"id":27345,"date":"2025-10-24T20:45:14","date_gmt":"2025-10-24T23:45:14","guid":{"rendered":"https:\/\/diariorepublica.com.ar\/web\/?p=27345"},"modified":"2025-10-24T20:45:16","modified_gmt":"2025-10-24T23:45:16","slug":"verstappen-volvio-a-dominar-en-mexico-y-colapinto-mostro-progreso-con-un-solido-cierre-en-la-fp2","status":"publish","type":"post","link":"https:\/\/diariorepublica.com.ar\/web\/index.php\/deportes\/2025\/10\/24\/verstappen-volvio-a-dominar-en-mexico-y-colapinto-mostro-progreso-con-un-solido-cierre-en-la-fp2\/","title":{"rendered":"Verstappen volvi\u00f3 a dominar en M\u00e9xico y Colapinto mostr\u00f3 progreso con un s\u00f3lido cierre en la FP2"},"content":{"rendered":"<p>El neerland\u00e9s Max Verstappen volvi\u00f3 a marcar el rumbo en la F\u00f3rmula 1 y se adue\u00f1\u00f3 del primer lugar en la segunda pr\u00e1ctica libre del Gran Premio de M\u00e9xico, disputado en el Aut\u00f3dromo Hermanos Rodr\u00edguez.<\/p>\n<p>En la segunda colocaci\u00f3n finaliz\u00f3 Charles Leclerc, quien mantuvo el ritmo competitivo de Ferrari y logr\u00f3 quedarse apenas por detr\u00e1s del l\u00edder, aunque con una diferencia que dej\u00f3 en evidencia la superioridad del neerland\u00e9s. El tercer puesto fue para una de las grandes promesas a seguir del fin de semana: Andrea Kimi Antonelli. El joven piloto italiano de Mercedes, que atraviesa su primera temporada completa en la categor\u00eda, sorprendi\u00f3 por su consistencia y demostr\u00f3 estar a la altura de los grandes nombres del campeonato.<\/p>\n<figure class=\"multimedia\" data-tadevel-template=\"web\/multimedia\" data-type=\"photo\">\n<div class=\"content\">\n<div class=\"sizer\" data-sizer=\"aspect-ratio\" data-tadevel-template=\"web\/aspect-ratio\">\n<p>La atenci\u00f3n argentina se centr\u00f3 en Franco Colapinto, que contin\u00faa adapt\u00e1ndose con firmeza a la m\u00e1xima categor\u00eda de monoplazas. El piloto de Alpine se qued\u00f3 con el decimoctavo lugar, superando a su experimentado compa\u00f1ero Pierre Gasly, quien no logr\u00f3 encontrar el ritmo y finaliz\u00f3 \u00faltimo, en el puesto 20. Para el joven de Pilar, el avance respecto a la primera pr\u00e1ctica signific\u00f3 un paso adelante en su proceso de aprendizaje, mostrando mayor confianza y control en las curvas r\u00e1pidas del trazado mexicano.<\/p>\n<p>Otra de las sorpresas fue el baj\u00f3n de Nico Hulkenberg, quien con el monoplaza de Kick Sauber no pudo repetir el buen rendimiento inicial y se ubic\u00f3 decimosexto, detr\u00e1s de su compa\u00f1ero Gabriel Bortoleto. El alem\u00e1n sufri\u00f3 con la degradaci\u00f3n de neum\u00e1ticos y la falta de tracci\u00f3n en la parte final del circuito, factores que complicaron a varios corredores a lo largo del d\u00eda.<\/p>\n<p>La jornada dej\u00f3 una certeza: Red Bull sigue siendo el rival a vencer y Verstappen mantiene la autoridad que lo llev\u00f3 a dominar toda la temporada. Detr\u00e1s, Ferrari y Mercedes se ilusionan con pelearle la clasificaci\u00f3n, mientras que Colapinto contin\u00faa sumando kil\u00f3metros valiosos en su debut dentro de la \u00e9lite del automovilismo mundial.<\/p>\n<h2><strong>Clasificaci\u00f3n final de la FP2 \u2013 GP de M\u00e9xico:<\/strong><\/h2>\n<ol>\n<li>Max Verstappen (Red Bull)<\/li>\n<li>Charles Leclerc (Ferrari)<\/li>\n<li>Andrea Kimi Antonelli (Mercedes)<\/li>\n<li>Lando Norris (McLaren)<\/li>\n<li>Lewis Hamilton (Ferrari)<\/li>\n<li>George Russell (Mercedes)<\/li>\n<li>Yuki Tsunoda (Red Bull)<\/li>\n<li>Fernando Alonso (Aston Martin)<\/li>\n<li>Carlos Sainz (Williams)<\/li>\n<li>Lance Stroll (Aston Martin)<\/li>\n<li>Liam Lawson (Racing Bulls)<\/li>\n<li>Oscar Piastri (McLaren)<\/li>\n<li>Esteban Ocon (Haas)<\/li>\n<li>Isack Hadjar (Racing Bulls)<\/li>\n<li>Gabriel Bortoleto (Kick Sauber)<\/li>\n<li>Nico Hulkenberg (Kick Sauber)<\/li>\n<li>Oliver Bearman (Haas)<\/li>\n<li><mark>Franco Colapinto (Alpine)<\/mark><\/li>\n<li>Alexander Albon (Williams)<\/li>\n<li>Pierre Gasly (Alpine)<\/li>\n<\/ol>\n<p>NA<\/p>\n<\/div>\n<\/div>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El neerland\u00e9s Max Verstappen volvi\u00f3 a marcar el rumbo en la F\u00f3rmula 1 y se adue\u00f1\u00f3 del primer lugar en<\/p>\n","protected":false},"author":1,"featured_media":27346,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[9],"tags":[],"class_list":["post-27345","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/27345"}],"collection":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/comments?post=27345"}],"version-history":[{"count":1,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/27345\/revisions"}],"predecessor-version":[{"id":27347,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/27345\/revisions\/27347"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/media\/27346"}],"wp:attachment":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/media?parent=27345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/categories?post=27345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/tags?post=27345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}