{"id":27405,"date":"2025-10-30T12:01:00","date_gmt":"2025-10-30T15:01:00","guid":{"rendered":"https:\/\/diariorepublica.com.ar\/web\/?p=27405"},"modified":"2025-10-30T11:02:18","modified_gmt":"2025-10-30T14:02:18","slug":"promueven-la-jerarquizacion-del-area-de-discapacidad-en-la-provincia","status":"publish","type":"post","link":"https:\/\/diariorepublica.com.ar\/web\/index.php\/sociedad\/2025\/10\/30\/promueven-la-jerarquizacion-del-area-de-discapacidad-en-la-provincia\/","title":{"rendered":"Promueven la jerarquizaci\u00f3n del \u00e1rea de discapacidad en la provincia"},"content":{"rendered":"<p>En Casa de Gobierno, el gobernador Ra\u00fal Jalil recibi\u00f3 al defensor del Pueblo, Dalmacio Mera, para planificar el trabajo orientado a jerarquizar las estructuras y \u00e1reas de discapacidad de la provincia.<\/p>\n<p>En la reuni\u00f3n tambi\u00e9n participaron los ministros de Gobierno, Seguridad y Justicia, Fernando Monguillot; de Salud, Johana Carrizo; de Hacienda y Obras P\u00fablicas, Juan Marchetti; la secretaria de Estado de Gabinete, Luz Mar\u00eda Soria, y la asesora General de Gobierno, Mara Murua.<\/p>\n<p>En la ocasi\u00f3n, se acord\u00f3 trabajar en una agenda integral sobre discapacidad, con la finalidad de poder jerarquizar las \u00e1reas que atienden esta problem\u00e1tica, adem\u00e1s de estructurar un esquema de actividades que tengan una visi\u00f3n articuladora entre las distintas realidades que se dan en las personas que afrontan las distintas condiciones de discapacidad.<\/p>\n<p>El mandatario provincial se comprometi\u00f3 a avanzar en la tem\u00e1tica y darle la relevancia que merece, adem\u00e1s de instrumentar todas las acciones necesarias para optimizar el servicio que actualmente brinda la provincia en esta materia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En Casa de Gobierno, el gobernador Ra\u00fal Jalil recibi\u00f3 al defensor del Pueblo, Dalmacio Mera, para planificar el trabajo orientado<\/p>\n","protected":false},"author":1,"featured_media":27406,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[3],"tags":[],"class_list":["post-27405","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sociedad"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/27405"}],"collection":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/comments?post=27405"}],"version-history":[{"count":1,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/27405\/revisions"}],"predecessor-version":[{"id":27407,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/27405\/revisions\/27407"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/media\/27406"}],"wp:attachment":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/media?parent=27405"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/categories?post=27405"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/tags?post=27405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}