{"id":27444,"date":"2025-11-03T17:14:46","date_gmt":"2025-11-03T20:14:46","guid":{"rendered":"https:\/\/diariorepublica.com.ar\/web\/?p=27444"},"modified":"2025-11-03T17:14:48","modified_gmt":"2025-11-03T20:14:48","slug":"el-sem-de-la-capital-certifico-el-nivel-de-ingles-a1-a-otros-250-alumnos","status":"publish","type":"post","link":"https:\/\/diariorepublica.com.ar\/web\/index.php\/locales\/2025\/11\/03\/el-sem-de-la-capital-certifico-el-nivel-de-ingles-a1-a-otros-250-alumnos\/","title":{"rendered":"El SEM de la Capital certific\u00f3 el nivel de ingl\u00e9s A1 a otros 250 alumnos"},"content":{"rendered":"<p dir=\"ltr\">En una jornada llena de emociones, el\u00a0Sistema Educativo Municipal (SEM)\u00a0de la Capital certific\u00f3 el nivel A1 de ingl\u00e9s alcanzado por\u00a0250 alumnos\u00a0de los niveles primario y secundario, en el marco del consolidado Programa Municipal de Ingl\u00e9s (PMI). Por segundo a\u00f1o consecutivo, se reconoci\u00f3 el avance de los estudiantes, ratificando la solidez de una propuesta pedag\u00f3gica que garantiza una formaci\u00f3n biling\u00fce de calidad en escuelas municipales capitalinas.<\/p>\n<p dir=\"ltr\">Un total de\u00a0180 alumnos de 6\u00b0 a\u00f1o\u00a0de educaci\u00f3n primaria recibieron su certificaci\u00f3n tras finalizar la trayectoria escolar. Paralelamente, 70 estudiantes de\u00a01\u00b0 y 2\u00b0 a\u00f1o de nivel secundario\u00a0hicieron lo propio, tras haber cursado los Talleres Complementarios de Intensificaci\u00f3n en Lengua Extranjera.<\/p>\n<p dir=\"ltr\">Por iniciativa de la Administraci\u00f3n de Planeamiento e Innovaci\u00f3n Educativa (APIE), en 2024 se implement\u00f3 el Examen Institucional de Lengua Extranjera, que permite a los egresados del 6\u00b0 a\u00f1o acreditar el nivel\u00a0A1\u00a0de ingl\u00e9s, conforme a lo establecido por el\u00a0Marco Com\u00fan Europeo de Referencia para Lenguas Extranjeras. Esta certificaci\u00f3n es una instancia fundamental que habilita a los alumnos a seguir avanzando en su formaci\u00f3n personal y acad\u00e9mica.<\/p>\n<p dir=\"ltr\">En este sentido,\u00a0la\u00a0Secretaria de Educaci\u00f3n y Cultura,\u00a0Marqueza Blanco, destac\u00f3: \u00abTenemos 180 alumnos del 6\u00b0 a\u00f1o del nivel primario, donde se aplica el Programa Municipal de Ingl\u00e9s hace tres a\u00f1os. Y en esta ocasi\u00f3n sumamos los alumnos de secundario que realizan actividades extracurriculares\u00bb, se\u00f1al\u00f3, resaltando el valor de la constancia institucional entregada.<\/p>\n<p dir=\"ltr\">Blanco aprovech\u00f3 la oportunidad para reconocer el esfuerzo de toda la comunidad educativa. \u00abAprovecho la oportunidad para destacar el compromiso de todos nuestros docentes que forman parte del equipo del Programa Municipal de Ingl\u00e9s y de las familias, que, sin lugar a duda, son un soporte fundamental en la educaci\u00f3n de nuestros alumnos\u00bb, afirm\u00f3.<\/p>\n<p dir=\"ltr\">Adem\u00e1s, resalt\u00f3 que la ense\u00f1anza se realiza \u00abde manera l\u00fadica, a trav\u00e9s del juego\u00bb, lo que garantiza la participaci\u00f3n activa de los ni\u00f1os, ya que la materia es obligatoria y forma parte de la curr\u00edcula desde el 1\u00b0 a\u00f1o.<\/p>\n<p dir=\"ltr\">Por su parte, la Administradora de Planeamiento e Innovaci\u00f3n Educativa (APIE),\u00a0Patricia Lobo, se refiri\u00f3 al\u00a0 modelo de ense\u00f1anza y aprendizaje \u00fanico en escuelas estatales del pa\u00eds: \u00abHace tres a\u00f1os que este programa naci\u00f3 con un sue\u00f1o simple pero muy potente. Este sue\u00f1o ten\u00eda que ver con la posibilidad de generar un dispositivo educativo que permitiese a nuestros alumnos de escuelas p\u00fablicas rendir ex\u00e1menes internacionales\u00bb, expres\u00f3.<\/p>\n<p dir=\"ltr\">Lobo record\u00f3 que la idea fue inicialmente considerada \u00abinviable o imposible\u00bb por muchos, pero que fue posible gracias a una \u00abfuerte decisi\u00f3n pol\u00edtica por parte del Intendente Gustavo Saadi de que este sue\u00f1o se haga realidad\u00bb. En la actualidad, m\u00e1s de\u00a08.000 estudiantes\u00a0han transitado y est\u00e1n transitando el programa, y destac\u00f3 que\u00a0m\u00e1s de 400 alumnos\u00a0se preparan para rendir ex\u00e1menes internacionales en diciembre, incluyendo a los valientes alumnos de secundaria que ser\u00e1n pioneros en un nuevo examen virtual de Cambridge.<\/p>\n<p dir=\"ltr\">\u00abPara nosotros este programa, desde el inicio, significa mucho m\u00e1s que ense\u00f1ar ingl\u00e9s. Para nosotros es una apuesta, una apuesta por la educaci\u00f3n p\u00fablica para mostrar que cuando hay acompa\u00f1amiento, cuando hay financiamiento sostenido, estas cosas suceden\u00bb, concluy\u00f3 Lobo, enviando un claro mensaje sobre la importancia de brindar estas posibilidades a todos.<\/p>\n<p dir=\"ltr\">\u00a0<\/p>\n<p dir=\"ltr\">Est\u00e1ndares Internacionales<\/p>\n<p dir=\"ltr\">El modelo pedag\u00f3gico del SEM se ve validado por resultados concretos. En diciembre pasado,\u00a083 estudiantes\u00a0del programa rindieron el Examen Internacional\u00a0Cambridge Pre A1 Starters, obteniendo valoraciones superiores a la media nacional y mundial.<\/p>\n<p dir=\"ltr\">Los reportes de la universidad de referencia destacaron que, en\u00a0comprensi\u00f3n de lectura y expresi\u00f3n escrita, los estudiantes se posicionan por\u00a0encima de la media nacional y mundial. En cuanto a la\u00a0comprensi\u00f3n auditiva, m\u00e1s del 50% de los candidatos alcanz\u00f3 la puntuaci\u00f3n m\u00e1xima. El \u00e1rea de\u00a0comprensi\u00f3n y producci\u00f3n oral\u00a0present\u00f3 los mejores resultados, con m\u00e1s del\u00a070% de los alumnos\u00a0consiguiendo la cantidad m\u00e1xima de 5 escudos.<\/p>\n<p dir=\"ltr\">Estos datos de 2023, que adem\u00e1s evidencian un rendimiento superior en todas las habilidades de la lengua inglesa respecto al a\u00f1o anterior, demuestran que la inversi\u00f3n del municipio capitalino por una formaci\u00f3n integral de calidad es una apuesta real por el futuro de sus estudiantes.<\/p>\n<p dir=\"ltr\">Presidieron el acto el Presidente del Concejo Deliberante,\u00a0Francisco Sosa; el Secretario de Gobierno,\u00a0Germ\u00e1n Kranevitter; la Secretaria de Educaci\u00f3n y Cultura,\u00a0Marqueza Blanco; el Director de Educaci\u00f3n,\u00a0N\u00e9stor Toledo; y la Administradora de Planeamiento e Innovaci\u00f3n Educativa,\u00a0Patricia Lobo.<\/p>\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En una jornada llena de emociones, el\u00a0Sistema Educativo Municipal (SEM)\u00a0de la Capital certific\u00f3 el nivel A1 de ingl\u00e9s alcanzado por\u00a0250<\/p>\n","protected":false},"author":1,"featured_media":27445,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[2],"tags":[],"class_list":["post-27444","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/27444"}],"collection":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/comments?post=27444"}],"version-history":[{"count":1,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/27444\/revisions"}],"predecessor-version":[{"id":27446,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/27444\/revisions\/27446"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/media\/27445"}],"wp:attachment":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/media?parent=27444"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/categories?post=27444"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/tags?post=27444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}