{"id":27456,"date":"2025-11-03T17:40:13","date_gmt":"2025-11-03T20:40:13","guid":{"rendered":"https:\/\/diariorepublica.com.ar\/web\/?p=27456"},"modified":"2025-11-03T17:40:15","modified_gmt":"2025-11-03T20:40:15","slug":"cronograma-de-pago-de-empleados-municipales","status":"publish","type":"post","link":"https:\/\/diariorepublica.com.ar\/web\/index.php\/locales\/2025\/11\/03\/cronograma-de-pago-de-empleados-municipales\/","title":{"rendered":"Cronograma de pago de empleados municipales"},"content":{"rendered":"<p>El municipio de la Capital anunci\u00f3 oficialmente el cronograma de pago de sueldos para los empleados municipales.<\/p>\n<p>Las fechas tienen este cronograma:<\/p>\n<ul>\n<li><strong>Mi\u00e9rcoles 5:<\/strong><\/li>\n<\/ul>\n<p>Planta Permanente<\/p>\n<p>Catamarca Ciudad Trabaja<\/p>\n<p>Contrato de Locaci\u00f3n de Obra<\/p>\n<ul>\n<li>Pago de sueldo por ventanilla: Todos los agentes en general de 8:00 a 13:00 y de 14:00 a 17:00 horas.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>El municipio de la Capital anunci\u00f3 oficialmente el cronograma de pago de sueldos para los empleados municipales. Las fechas tienen<\/p>\n","protected":false},"author":1,"featured_media":27457,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[2],"tags":[],"class_list":["post-27456","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/27456"}],"collection":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/comments?post=27456"}],"version-history":[{"count":1,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/27456\/revisions"}],"predecessor-version":[{"id":27458,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/27456\/revisions\/27458"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/media\/27457"}],"wp:attachment":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/media?parent=27456"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/categories?post=27456"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/tags?post=27456"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}