{"id":34620,"date":"2026-09-02T07:42:29","date_gmt":"2026-09-02T10:42:29","guid":{"rendered":"https:\/\/diariorepublica.com.ar\/web\/?p=34620"},"modified":"2026-09-02T07:42:31","modified_gmt":"2026-09-02T10:42:31","slug":"charlotte-caniggia-tuvo-el-derecho-a-replica-con-su-mama-mariana-nannis","status":"publish","type":"post","link":"https:\/\/diariorepublica.com.ar\/web\/index.php\/espectaculos\/2026\/09\/02\/charlotte-caniggia-tuvo-el-derecho-a-replica-con-su-mama-mariana-nannis\/","title":{"rendered":"Charlotte Caniggia tuvo el Derecho a R\u00e9plica con su mam\u00e1, Mariana Nannis"},"content":{"rendered":"<article class=\"article-body first\">\n<div class=\"article-content\">\n<div class=\"news-body-paragraph\">\n<p id=\"p-1788318423730-65601\" class=\"\" data-start=\"151\" data-end=\"401\">En medio de una noche cargada de emoci\u00f3n,\u00a0<strong data-start=\"193\" data-end=\"215\">Charlotte Caniggia<\/strong>\u00a0tuvo su esperado Derecho a R\u00e9plica y recibi\u00f3 un llamado telef\u00f3nico de\u00a0<strong data-start=\"286\" data-end=\"304\">Mariana Nannis<\/strong>, protagonizando uno de los momentos m\u00e1s conmovoderes de la gala del martes 1 de septiembre en\u00a0<strong data-start=\"357\" data-end=\"400\">Gran Hermano Generaci\u00f3n Dorada (Telefe)<\/strong>.<\/p>\n<\/div>\n<\/div>\n<\/article>\n<article class=\"article-body par-2\">\n<div class=\"article-content\">\n<div class=\"news-body-paragraph\">\n<p id=\"p-1788318423730-75195\" data-start=\"403\" data-end=\"688\">La participante ven\u00eda reflexionando sobre el v\u00ednculo con su familia y, en las \u00faltimas horas, tuvo la posibilidad de escuchar directamente a su madre a trav\u00e9s de una llamada telef\u00f3nica. Durante la charla, Mariana la alent\u00f3 a seguir adelante, le pidi\u00f3 que fuera por la copa y le transmiti\u00f3 todo su apoyo.<\/p>\n<article class=\"article-body\">\n<div class=\"article-content\">\n<div class=\"news-body-paragraph\">\n<p id=\"p-1788318423730-69863\" data-start=\"690\" data-end=\"943\" data-is-last-node=\"\" data-is-only-node=\"\">Emocionada por volver a escucharla, la participante le respondi\u00f3 desde la casa y cont\u00f3 c\u00f3mo estaba viviendo las \u00faltimas jornadas dentro del reality:\u00a0<strong data-start=\"833\" data-end=\"942\">\u201c<em>Hola, mam\u00e1. Estoy ac\u00e1, aguantando a las locas estas. Me est\u00e1n volviendo loca. Termino ac\u00e1 y voy a verte<\/em>\u201d<\/strong>.<\/p>\n<\/div>\n<\/div>\n<\/article>\n<article class=\"article-body\">\n<div class=\"article-content\">\n<div class=\"news-body-paragraph\">\n<p id=\"p-1788318334584-57164\" class=\"\">Luego, fue el turno de hablar de la modelo, quien le dio un gran consejo de vida y le expres\u00f3 todo su amor: \u201c<em>Para m\u00ed, vas a ganar. Venite a Marbella donde la vida es bella, pero siempre ganadora.\u00a0<strong>Siempre hay uno m\u00e1s malo que vos y uno m\u00e1s bueno que vos<\/strong>. As\u00ed que tranquila, que vos vas a ganar.\u00a0<strong>Te quiero mucho y te llevo siempre en mi coraz\u00f3m. Besito, mi amor<\/strong><\/em>\u00a0\u201d, atin\u00f3 a decir. Y su hija cerr\u00f3: \u201c<em>\u00a1Te amo! Gracias por llamar<\/em>\u00ab.<\/p>\n<\/div>\n<\/div>\n<\/article>\n<article class=\"article-body third-p\">\n<div class=\"article-content\">\n<div class=\"news-body-paragraph\">\n<div id=\"embed22_wrap\" class=\"embed_cont type_freetext\" contenteditable=\"false\">\n<div id=\"embed22_content\" class=\"embed_content\">\n<div id=\"embed22_embed\">\n<div id=\"p-1788317771269-42594\">\n<div id=\"dailymotion-instance-500e0841-7a94-bbc5-ff86-0457a8d4c9a7\" class=\"dailymotion-player-root dailymotion-player-xx206\">\n<div class=\"dailymotion-player-wrapper\"><iframe loading=\"lazy\" class=\"dailymotion-player\" title=\"Dailymotion video player - Charlotte Caniggia se emocion\u00f3 profundamente en su Derecho a R\u00e9plica\" src=\"https:\/\/geo.dailymotion.com\/player\/xx206.html?video=xb379qm&amp;customConfig%5Bkeyvalues%5D=section%3Dprimiciasya%26tags%3Dmariana-nannis%2Ccharlotte-caniggia%2Cgran-hermano\" width=\"100%\" height=\"100%\" frameborder=\"0\" data-gtm-yt-inspected-8=\"true\" data-gtm-yt-inspected-31521157_77=\"true\" data-mce-fragment=\"1\"><\/iframe><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"p-1788317771269-53122\" class=\"embed_wrapper-cont\">\n<div id=\"embed22_epigrafe\" class=\"embed_epigrafe\">\u00a0<\/div>\n<\/div>\n<\/div>\n<p id=\"p-1788322853542-24396\">C\u00f3mo fue la charla de Alex y Charlotte Caniggia<\/p>\n<p id=\"p-1788322996009-88465\" class=\"\">La emoci\u00f3n sigui\u00f3 creciendo para\u00a0<strong>Charlotte Caniggia<\/strong>\u00a0cuando recibi\u00f3 otro mensaje inesperado de su familia, esta vez de parte de su hermano\u00a0<strong>Alex Caniggia<\/strong>, quien quiso acompa\u00f1arla a la distancia en uno de los momentos m\u00e1s importantes de su participaci\u00f3n en\u00a0<strong>Gran Hermano<\/strong>.<\/p>\n<p id=\"p-1788322996009-9897\" class=\"\">\u201c<em><strong>Hermana m\u00eda de mi vida. Estoy pero tan, tan orgulloso de vos. Te amo, sis<\/strong><\/em>\u00a0\u201d, expres\u00f3 Alex en el mensaje que lleg\u00f3 hasta la casa y que r\u00e1pidamente conmovi\u00f3 a Charlotte.<\/p>\n<p id=\"p-1788322996009-60311\" class=\"\">El medi\u00e1tico continu\u00f3 con unas sentidas palabras de apoyo para su hermana: \u201c<em><strong>Estoy lejos, pero mi coraz\u00f3n est\u00e1 siempre con vos. Te lo ganaste vos estar ah\u00ed, donde est\u00e1s ahora, en la final. Semanas, meses luch\u00e1ndola. Nadie te puede venir a decir nada, porque vos sola te ganaste el puesto de estar en esa final<\/strong>\u201d<\/em>.<\/p>\n<p id=\"p-1788322996009-14342\" class=\"\">En esa misma l\u00ednea, le record\u00f3 que el resultado de la competencia no modifica todo lo que consigui\u00f3 durante su recorrido: \u201c<em><strong>Pierdas o ganes, sis. Sos una guerrera de la vida, una luchadora. Entonces, disfrut\u00e1 la final. Ten\u00e9s que ser la ganadora de este Gran Hermano, sis. \u00a1Vamos con todo! \u00a1Te amo!<\/strong><\/em>\u00a0\u201d.<\/p>\n<p id=\"p-1788322996009-42331\" class=\"\"><em>\u201c<strong>Ay, gracias<\/strong>\u201d,<\/em>\u00a0respondi\u00f3 la participante con pocas palabras, sin poder ocultar la emoci\u00f3n frente a las c\u00e1maras. Luego explic\u00f3 por qu\u00e9 le resulta tan dif\u00edcil exteriorizar sus sentimientos en p\u00fablico: \u201c<em><strong>Me cuesta llorar, pero gracias. Yo no me lo permito<\/strong><\/em>\u00a0\u201d.<\/p>\n<p id=\"p-1788322996009-95454\">De esta manera, Charlotte dej\u00f3 ver una faceta mucho m\u00e1s \u00edntima y vulnerable, en medio de la enorme expectativa que genera su llegada a la final de Gran Hermano.<\/p>\n<div id=\"1896583-LibreSinLimite-429069822_wrap\" class=\"embed_cont type_imagen\" contenteditable=\"false\">\n<div id=\"1896583-LibreSinLimite-429069822_content\" class=\"embed_content\"><img decoding=\"async\" id=\"1896583-LibreSinLimite-429069822_embed\" title=\"\" src=\"https:\/\/media.a24.com\/p\/ef12802d0bdcec2f19502923bf8ef342\/adjuntos\/296\/imagenes\/009\/808\/0009808325\/1200x0\/smart\/alex-caniggia-y-charlotte-gh.png\" alt=\"\" width=\"1200\" height=\"undefined\" \/><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n<\/div>\n<\/div>\n<\/article>\n\n\n<p>primiciasya.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En medio de una noche cargada de emoci\u00f3n,\u00a0Charlotte Caniggia\u00a0tuvo su esperado Derecho a R\u00e9plica y recibi\u00f3 un llamado telef\u00f3nico de\u00a0Mariana<\/p>\n","protected":false},"author":1,"featured_media":34621,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[7],"tags":[],"class_list":["post-34620","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espectaculos"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/34620"}],"collection":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/comments?post=34620"}],"version-history":[{"count":1,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/34620\/revisions"}],"predecessor-version":[{"id":34622,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/34620\/revisions\/34622"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/media\/34621"}],"wp:attachment":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/media?parent=34620"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/categories?post=34620"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/tags?post=34620"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}