{"id":394,"date":"2023-03-27T11:18:15","date_gmt":"2023-03-27T14:18:15","guid":{"rendered":"https:\/\/diariorepublica.com.ar\/web\/?p=394"},"modified":"2023-03-27T11:18:15","modified_gmt":"2023-03-27T14:18:15","slug":"catamarca-tuvo-un-70-de-ocupacion-hotelera-el-fin-de-semana-largo-de-marzo","status":"publish","type":"post","link":"https:\/\/diariorepublica.com.ar\/web\/index.php\/sociedad\/2023\/03\/27\/catamarca-tuvo-un-70-de-ocupacion-hotelera-el-fin-de-semana-largo-de-marzo\/","title":{"rendered":"Catamarca tuvo un 70% de ocupaci\u00f3n hotelera el fin de semana largo de marzo"},"content":{"rendered":"<p>El fin de semana largo de marzo la ocupaci\u00f3n hotelera promedio en Catamarca fue del 70%, marcando un piso muy interesante para el pr\u00f3ximo fin de semana extra largo que se avecina, en Semana Santa.<br \/>Seg\u00fan datos relevados por la Direcci\u00f3n de Calidad Tur\u00edstica, dependiente de la Secretar\u00eda de Gesti\u00f3n Tur\u00edstica del Ministerio de Cultura, Turismo y Deporte, del 24 al 26 de marzo 12.488 turistas se alojaron en la provincia, con un promedio de estad\u00eda de dos d\u00edas.<br \/>En t\u00e9rminos de impacto econ\u00f3mico, el movimiento tur\u00edstico del fin de semana largo fue de 191,4 millones de pesos, monto global que se distribuye en toda la cadena de valor del sector y que contempla un gasto diario promedio, fijado en 10.217 pesos por persona.<br \/>\u201cEstamos muy satisfechos con el movimiento tur\u00edstico de ese fin de semana, que nos va marcando un piso para lo que va a ser Semana Santa, donde esperamos n\u00fameros a\u00fan m\u00e1s importantes\u201d, se\u00f1al\u00f3 el ministro de Cultura, Turismo y Deporte, Roberto Brunello quien adem\u00e1s destac\u00f3 las propuestas que est\u00e1n generando tanto municipios como privados para atraer a los turistas en esta \u00e9poca del a\u00f1o.<br \/>El fin de semana largo de marzo, que coincidi\u00f3 con el feriado del 24 de marzo por el D\u00eda de la Memoria, tuvo como destinos m\u00e1s elegidos en Catamarca, Antofagasta de la Sierra y El Rodeo con el 100% de ocupaci\u00f3n hotelera, seguida de municipios como Las Juntas, con el 90%, Huillapima 85%, Andalgal\u00e1 83%, Fiambal\u00e1, El Alto, Pacl\u00edn y Fray Mamerto Esqui\u00fa con el 80%; Santa Rosa con el 75%, La Puerta, Pom\u00e1n y Capital con el 70% y Tinogasta con el 60% de ocupaci\u00f3n hotelera.<br \/>A nivel pa\u00eds, el Ministerio de Turismo y Deportes de la Naci\u00f3n inform\u00f3 que viajaron por Argentina 880 mil personas y gastaron 26.467 millones de pesos en alimentos, bebidas, alojamiento, transporte, recreaci\u00f3n y compras diversas, lo que contempla un gasto diario promedio de $10.590 pesos y una estad\u00eda promedio de 2,8 noches.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El fin de semana largo de marzo la ocupaci\u00f3n hotelera promedio en Catamarca fue del 70%, marcando un piso muy<\/p>\n","protected":false},"author":2,"featured_media":395,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[3],"tags":[],"class_list":["post-394","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sociedad"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/394"}],"collection":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/comments?post=394"}],"version-history":[{"count":1,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/394\/revisions"}],"predecessor-version":[{"id":396,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/posts\/394\/revisions\/396"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/media\/395"}],"wp:attachment":[{"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/media?parent=394"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/categories?post=394"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariorepublica.com.ar\/web\/index.php\/wp-json\/wp\/v2\/tags?post=394"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}